{"id":7278,"date":"2012-07-13T19:04:24","date_gmt":"2012-07-14T00:04:24","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/?p=7278"},"modified":"2012-07-13T19:16:02","modified_gmt":"2012-07-14T00:16:02","slug":"sus-contrasenas-si-estan-seguras","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2012\/07\/13\/sus-contrasenas-si-estan-seguras\/","title":{"rendered":"Sus contrase\u00f1as si est\u00e1n seguras?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-7286\" title=\"locks\" src=\"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/07\/locks-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/07\/locks-300x177.jpg 300w, https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/07\/locks.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En un mundo cada vez m\u00e1s digital, nuestra informaci\u00f3n personal es cada vez menos privada. En sitios como FaceBook, Yahoo, Google, y en las p\u00e1ginas de los bancos en l\u00ednea, se encuentra informaci\u00f3n que puede considerarse ya cr\u00edtica para nuestra seguridad y privacidad.<\/p>\n<p>Dicha informaci\u00f3n se encuentra a veces a una contrase\u00f1a de distancia de las manos equivocadas. Por ende tener una buena pol\u00edtica frente a estas contrase\u00f1as es fundamental.<\/p>\n<p>Nada nos proteger\u00e1 frente a los posibles ataques de hackers que buscan estas contrase\u00f1as en los sitios que las coleccionan. Por m\u00e1s seguros que sean, nada es absolutamente impenetrable.<\/p>\n<p>Basta con leer en las noticias acerca de dos ataques recientes de hackers: el primero sobre Linked In, en la que 6.5 millones de contrase\u00f1as de ese sitio se hicieron p\u00fablicas; y el segundo, esta semana sobre Yahoo, <a href=\"http:\/\/www.vanguardia.com\/actualidad\/tecnologia\/165153-yahoo-admite-robo-de-450000-nombres-y-contrasenas-de-correo-de-sus-usua\" target=\"_blank\">de donde un grupo de hackers de Ucrania se llevaron 450.000 contrase\u00f1as que luego hicieron p\u00fablicas en su p\u00e1gina Web<\/a>.<\/p>\n<p><strong>Nosotros podemos protegernos o al menos reducir el impacto que tiene sobre nuestra privacidad estos ataques escogiendo una buena pol\u00edtica de claves.<\/strong><\/p>\n<p><strong>La primera regla es elemental: tener claves diferentes para todos los sitios importantes.<\/strong> Claro, es muy f\u00e1cil tener que aprenderse tan s\u00f3lo una clave para todos nuestros accesos digitales, pero si una de ellas es revelada, como ya vimos que sucede, su acceso a todos los dem\u00e1s sitios queda igualmente comprometido, pues no dude que los hackers tienen programas que autom\u00e1ticamente prueban las claves obtenidas en una multitud de sitios importantes.<\/p>\n<p><strong>La segunda regla es tener claves complejas: que sus contrase\u00f1as tengan al menos 8 caracteres y que estos incluyan \u2013en lo posible- n\u00fameros, letras may\u00fasculas y min\u00fasculas y caracteres especiales, como \u201c#\u201d o \u201c%\u201d.<\/strong><\/p>\n<p>Evite utilizar claves elementales, como \u201c123456\u201d, que es de paso <a href=\"http:\/\/dienteazulds.wordpress.com\/2009\/05\/12\/las-500-contrasenas-mas-comunes\/\" target=\"_blank\">la clave m\u00e1s popular del mundo<\/a> y por ende la primera que intentan los hackers. Otras claves d\u00e9biles son aquellas que utilizan palabras completas como \u201cbaseball\u201d, \u201cninja\u201d, \u201cpassword\u201d, pues provienen directamente de un diccionario, otra de las estrategias utilizadas por los piratas.<\/p>\n<p><strong>Los expertos recomiendan que tengamos al menos tres tipos de claves: una muy f\u00e1cil de recordar para utilizar en aquellos sitios en los que no se almacena informaci\u00f3n cr\u00edtica.\u00a0 Una mediana, para utilizar en sitios que almacenan informaci\u00f3n personal, como FaceBook o Twitter, y finalmente una bien segura y dif\u00edcil para utilizar en los sitios en los que almacena informaci\u00f3n financiera, como bancos o tiendas en l\u00ednea.<\/strong><\/p>\n<p>Y siguiendo con la primera regla, tanto como para las contrase\u00f1as de mediana dificultad como para las de alta seguridad, utilice peque\u00f1as desviaciones para diferenciar cada sitio. As\u00ed, a\u00f1ada \u201cFBook\u201d a su contrase\u00f1a base para FaceBook, por ejemplo.<\/p>\n<p>Claro, tarde o temprano llegamos a un nivel en que tendremos demasiadas contrase\u00f1as para recordar. Es ah\u00ed cuando un programa como \u201c<a title=\"P\u00e1gina Web de KeePass\" href=\"http:\/\/keepass.info\/\" target=\"_blank\">Kee Pass<\/a>\u201d viene a ser muy \u00fatil, pues nos permite almacenar todas nuestras contrase\u00f1as detr\u00e1s de una sola clave, que obviamente debe ser bastante compleja (quiz\u00e1s una frase completa)..<\/p>\n<p>En este tema de la seguridad inform\u00e1tica nunca estaremos totalmente protegidos, pero siguiendo estos consejos podemos reducir nuestros riesgos. No hagan como alguien que conoc\u00ed que llevaba en un papelito de su billetera las claves de las tarjetas d\u00e9bito. Por supuesto, el d\u00eda que la robaron se llevaron todo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mundo cada vez m\u00e1s digital, nuestra informaci\u00f3n personal es cada vez menos privada. En sitios como FaceBook, Yahoo, Google, y en las p\u00e1ginas de los bancos en l\u00ednea, se encuentra informaci\u00f3n que puede considerarse ya cr\u00edtica para nuestra seguridad y privacidad. Dicha informaci\u00f3n se encuentra a veces a una contrase\u00f1a de distancia de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2012\/07\/13\/sus-contrasenas-si-estan-seguras\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":7286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[112,61,110],"tags":[193,196,194,195,192],"class_list":["post-7278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas-de-tecnologia","category-internet","category-tecnologia-en-accion","tag-contrasenas","tag-hackers","tag-linked-in","tag-seguridad-informatica","tag-yahoo","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/07\/locks.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2nF3t-1To","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/comments?post=7278"}],"version-history":[{"count":12,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7278\/revisions"}],"predecessor-version":[{"id":7289,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7278\/revisions\/7289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media\/7286"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media?parent=7278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/categories?post=7278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/tags?post=7278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}