{"id":7252,"date":"2012-06-29T08:18:05","date_gmt":"2012-06-29T13:18:05","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/?p=7252"},"modified":"2012-06-29T08:18:05","modified_gmt":"2012-06-29T13:18:05","slug":"las-gafas-futuristas-de-google","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2012\/06\/29\/las-gafas-futuristas-de-google\/","title":{"rendered":"Las gafas futuristas de Google"},"content":{"rendered":"<div id=\"attachment_7256\" style=\"width: 263px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7256\" class=\"size-medium wp-image-7256\" src=\"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos-263x300.jpg\" alt=\"Las &quot;Google Glasses&quot;\" width=\"263\" height=\"300\" srcset=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos-263x300.jpg 263w, https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos-900x1024.jpg 900w, https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos.jpg 950w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/a><p id=\"caption-attachment-7256\" class=\"wp-caption-text\">Las &quot;Google Glasses&quot;<\/p><\/div>\n<p>En la famosa pel\u00edcula de acci\u00f3n, <a href=\"http:\/\/es.wikipedia.org\/wiki\/The_Terminator\" target=\"_blank\">\u201cTerminator\u201d,<\/a> las m\u00e1quinas env\u00edan a un cyborg desde el a\u00f1o 2029, a trav\u00e9s de una m\u00e1quina del tiempo, para exterminar a la madre de quien ser\u00eda el l\u00edder de la resistencia humana. Este cyborg, llevado a la pantalla y al estrellato por Arnold Schwarzenegger, ten\u00eda en su visi\u00f3n informaci\u00f3n adicional frente a lo que ve\u00edan sus ojos de c\u00e1maras, como la identificaci\u00f3n de armas, distancias, reconocimiento de caras, etc.<\/p>\n<p>Esa tecnolog\u00eda, que ve\u00edamos con ojos sorprendidos en los cines de hace m\u00e1s de 25 a\u00f1os, ya est\u00e1 cerca de ser una realidad, cortes\u00eda de Google.<\/p>\n<p><strong>Se llaman las \u201cgafas de Google\u201d o \u201cGoogle Glasses\u201d y es uno de esos proyectos futuristas que llevan ya algunos a\u00f1os desarroll\u00e1ndose en forma muy secreta en lo que ellos llaman los \u201cGoogle X Labs\u201d.<\/strong><\/p>\n<p>Despu\u00e9s de unos meses de silencio en los medios, las gafas esta semana volvieron a la luz p\u00fablica cuando unos prototipos avanzados se \u201crobaron\u201d el show de \u201cGoogle I\/O 2012\u201d, la conferencia para desarrolladores de Google que se lleva a cabo en San Francisco.<\/p>\n<p>En esta conferencia se mostraron a <a href=\"http:\/\/youtu.be\/fxX8iQgpFkk\" target=\"_blank\">unos paracaidistas luciendo estas gafas especiales, cuyo veloz descenso era transmitido en directo y en primer plano<\/a>, a unas pantallas gigantes ubicadas en el centro de convenciones en donde se desarrollaba el evento. (Ayudados por unas antenas satelitales dirigidas directamente hacia ellos, ya que la se\u00f1al que emiten las gafas no es demasiado fuerte).<\/p>\n<p><strong>Estas gafas est\u00e1n compuestas de procesador, micr\u00f3fono, c\u00e1mara, bater\u00eda, memoria y una mini pantalla,<\/strong> que le permiten a quien las usa, transmitir en vivo lo que est\u00e1n viendo sus ojos, obtener informaci\u00f3n sobre el clima o sobre c\u00f3mo llegar a un determinado lugar, hablar con otras personas, recomendar un restaurante y otros muchos usos que todav\u00eda est\u00e1n en etapa conceptual.<\/p>\n<p>La mini pantalla cubre un ojo. El otro ojo es el que lleva la mini c\u00e1mara. Aunque no es claro el dise\u00f1o final, se cree que tendr\u00e1 un par de botones de control en una banda lateral que va desde el ojo a la oreja. Todo este paquete, afirma el dise\u00f1ador, no pesa m\u00e1s que algunas gafas convencionales.<\/p>\n<p>En este video se puede apreciar el concepto de las gafas seg\u00fan Google:<\/p>\n<div class=\"embed-container\"><iframe loading=\"lazy\" title=\"Project Glass: One day...\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/9c6W4CCU9M4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Aunque Google fue enf\u00e1tico en afirmar que las gafas est\u00e1n a\u00fan en desarrollo, a los asistentes al evento se les ofreci\u00f3 una versi\u00f3n intermedia que se entregar\u00e1 a principios del a\u00f1o entrante y que tiene un costo de 1.500 d\u00f3lares.<\/p>\n<p><strong>La versi\u00f3n definitiva deber\u00e1 estar disponible para el p\u00fablico en general un a\u00f1o despu\u00e9s, a un precio mucho m\u00e1s comercial, similar al de los celulares inteligentes de hoy.<\/strong><\/p>\n<p>Entonces, si todo sale como lo tiene planeado Google, veremos en el 2014 las gafas en el mercado, unos 15 a\u00f1os antes del \u201cfuturo\u201d dominado por robots de la famosa pel\u00edcula.<\/p>\n<p><strong>Es indudable que estas gafas son un producto revolucionario.<\/strong> Tener la informaci\u00f3n completa sobre la realidad que se est\u00e1 \u201cviendo y viviendo\u201d en tiempo real es para algunos incluso fundamental. Las gafas son, en cierta manera, la evoluci\u00f3n de los celulares de hoy. Una evoluci\u00f3n que vino del futuro, en los ojos de los robots de \u201cTerminator\u201d, que viene esta vez a \u201caniquilar\u201d a sus competidores en el mundo digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la famosa pel\u00edcula de acci\u00f3n, \u201cTerminator\u201d, las m\u00e1quinas env\u00edan a un cyborg desde el a\u00f1o 2029, a trav\u00e9s de una m\u00e1quina del tiempo, para exterminar a la madre de quien ser\u00eda el l\u00edder de la resistencia humana. Este cyborg, llevado a la pantalla y al estrellato por Arnold Schwarzenegger, ten\u00eda en su visi\u00f3n informaci\u00f3n &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2012\/06\/29\/las-gafas-futuristas-de-google\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":7256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[112,75,110],"tags":[188,59,185,187,186],"class_list":["post-7252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas-de-tecnologia","category-equipos-de-computo","category-tecnologia-en-accion","tag-gafas-de-google","tag-google","tag-google-glasses","tag-google-io-conference","tag-google-x-labs","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2012\/06\/Google_glass_photos.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2nF3t-1SY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/comments?post=7252"}],"version-history":[{"count":6,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7252\/revisions"}],"predecessor-version":[{"id":7261,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/7252\/revisions\/7261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media\/7256"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media?parent=7252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/categories?post=7252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/tags?post=7252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}