{"id":6802,"date":"2011-11-28T13:07:35","date_gmt":"2011-11-28T18:07:35","guid":{"rendered":"http:\/\/renedimarco.wordpress.com\/?p=6802"},"modified":"2012-04-12T23:29:02","modified_gmt":"2012-04-12T23:29:02","slug":"google-map","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2011\/11\/28\/google-map\/","title":{"rendered":"Google Map$"},"content":{"rendered":"<div id=\"attachment_6989\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2011\/11\/powerhour_print_route_with_google_maps.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6989\" class=\"size-medium wp-image-6989\" title=\"Google Maps, deja de ser gratis.\" src=\"http:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2011\/11\/powerhour_print_route_with_google_maps-300x218.jpg\" alt=\"Google Maps, deja de ser gratis.\" width=\"300\" height=\"218\" srcset=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2011\/11\/powerhour_print_route_with_google_maps-300x218.jpg 300w, https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2011\/11\/powerhour_print_route_with_google_maps.jpg 399w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-6989\" class=\"wp-caption-text\">Google Maps, deja de ser gratis.<\/p><\/div>\n<p>En la era de los servicios gratuitos en Internet, el rey acaba de dar un fuerte timonazo de 180 grados en sus pol\u00edticas: <strong>el uso de los mapas de Google tendr\u00e1 costo a partir del a\u00f1o 2012.<\/strong><\/p>\n<p>Hoy en d\u00eda m\u00e1s de un mill\u00f3n cien mil sitios o aplicaciones en Internet utilizan los mapas de Google. Sitios relacionados con viajes, gu\u00edas de ciudad, venta de finca ra\u00edz, dependen y utilizan muy fuertemente estos mapas.<!--more--><\/p>\n<p><strong>Lo que Google ha dicho es que s\u00f3lo aquellos sitios que consulten m\u00e1s de 25.000 veces al d\u00eda sus mapas deber\u00e1n comprar su licencia Premium, que comienza en 10.000 d\u00f3lares por a\u00f1o, unos 20 millones de pesos.<\/strong> Bajo estas condiciones, Google calcula que habr\u00e1n unos 4.000 sitios que deber\u00e1n licenciarse, menos del 0,35% del volumen global.<\/p>\n<p>Los dem\u00e1s sitios o aplicaciones podr\u00e1n seguir utilizando el servicio de mapas de manera gratuita, aunque con ciertas funciones limitadas en comparaci\u00f3n a la versi\u00f3n Premium.<\/p>\n<p>Personalmente estoy de acuerdo en que ciertos servicios se cobren, pues producirlos definitivamente cuestan. No se puede negar la calidad y utilidad de los mapas de Google: ayudan a ubicar un inmueble en venta o a ver qu\u00e9 restaurantes est\u00e1n cerca de donde estamos en un momento dado, por ejemplo.<\/p>\n<p>Hay sin duda muchos recursos involucrados en obtener dichos mapas, desde los servicios satelitales, hasta los censos de ciudad, pasando por los enormes supercomputadores necesarios para ordenar y almacenar toda esta informaci\u00f3n que, dicho sea de paso, es la m\u00e1s completa de todas, pues los mapas de Google est\u00e1n muy por encima de su competencia.<\/p>\n<p><strong>As\u00ed que la nueva pol\u00edtica de cobro por su utilizaci\u00f3n tiene sentido, especialmente para aquellos sitios que se benefician directamente de ellos. Cobrando ayudar\u00e1 a que el servicio siga mejorando para beneficio del resto de internautas.<\/strong><\/p>\n<p>Pero tambi\u00e9n hago votos para que se mantenga el esp\u00edritu fundamental del Internet, en el que la informaci\u00f3n est\u00e1 disponible para todos, as\u00ed sea de forma limitada; este cobro entonces no debe ser global.<\/p>\n<p><strong>Es la tendencia que cobra fuerza en esta etapa de la Web: servicios b\u00e1sicos disponibles libremente, al lado de servicios Premium que ofrecen mayores funcionalidades acequibles a trav\u00e9s del pago de una tarifa, que de paso asegura la viabilidad econ\u00f3mica para quienes lo producen.<\/strong> Es, sin duda, el \u00abmapa\u00bb ideal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la era de los servicios gratuitos en Internet, el rey acaba de dar un fuerte timonazo de 180 grados en sus pol\u00edticas: el uso de los mapas de Google tendr\u00e1 costo a partir del a\u00f1o 2012. Hoy en d\u00eda m\u00e1s de un mill\u00f3n cien mil sitios o aplicaciones en Internet utilizan los mapas de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/2011\/11\/28\/google-map\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":6989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[112,61,110],"tags":[59,60,119],"class_list":["post-6802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas-de-tecnologia","category-internet","category-tecnologia-en-accion","tag-google","tag-google-maps","tag-servicios-premium","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/files\/2011\/11\/powerhour_print_route_with_google_maps.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2nF3t-1LI","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/6802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/comments?post=6802"}],"version-history":[{"count":4,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/6802\/revisions"}],"predecessor-version":[{"id":6986,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts\/6802\/revisions\/6986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media\/6989"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/media?parent=6802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/categories?post=6802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/tags?post=6802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}