{"id":112,"count":28,"description":"Empresas l\u00edderes en Tecnolog\u00eda a nivel Mundial, que crean tendencias y nuevos segmentos de uso. Caso: Google, Apple, Samsung, RIM, etc.","link":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/category\/empresas-de-tecnologia\/","name":"Empresas de Tecnolog\u00eda","slug":"empresas-de-tecnologia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/categories\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.vanguardia.com\/tecnologiaviva\/wp-json\/wp\/v2\/posts?categories=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}