{"id":91,"date":"2019-06-05T16:24:08","date_gmt":"2019-06-05T16:24:08","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/rock-and-words\/?p=91"},"modified":"2019-06-05T16:24:08","modified_gmt":"2019-06-05T16:24:08","slug":"evoluciona-horkheimer-adorno-y-pearl-jam","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/06\/05\/evoluciona-horkheimer-adorno-y-pearl-jam\/","title":{"rendered":"\u00a1Evoluciona! Horkheimer, Adorno y Pearl Jam"},"content":{"rendered":"\n<p>\u00bfQu\u00e9 de bueno tiene la modernidad? \u00bfEs el progreso sin\u00f3nimo de felicidad? \u00bfDe qu\u00e9 nos sirve la tecnolog\u00eda si al final perdemos nuestra humanidad? Estas preguntas son vitales para entender la obra de Max Horkheimer y Theodor Adorno, dos pensadores alemanes de la famosa Escuela de Frankfurt y conocidos por su teor\u00eda cr\u00edtica.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/soonatas.files.wordpress.com\/2018\/02\/do_the_evolution_pearl_jam.jpg?w=1920&amp;h=1000&amp;crop=1\" alt=\"\" \/><\/figure>\n\n\n\n<p>La ilustraci\u00f3n, ese\nsue\u00f1o que se impone con los ideales de los revolucionarios franceses, no es tan\nbuena como nos la han presentado. Seg\u00fan la ideolog\u00eda dominante, este proceso iluminativo\ndebe poner en un pedestal a la raz\u00f3n, la cual nos orientar\u00e1 para lograr una\nsociedad m\u00e1s racional y menos barb\u00e1rica; as\u00ed las cosas, nada de malo puede esperarse\nde \u201clo racional\u201d en tanto s\u00f3lo puede traer progreso a la vez que supera el\noscurantismo y la dogm\u00e1tica. Pero como reza el dicho popular: eso es muy bueno\npara ser verdad.<\/p>\n\n\n\n<p>En su famosa obra \u201c<em>Dial\u00e9ctica de la Ilustraci\u00f3n<\/em>\u201d Adorno y Horkheimer nos muestran c\u00f3mo la Ilustraci\u00f3n nos hizo promesas que no pudo (ni podr\u00e1 cumplir). El hombre no se ha emancipado, no se ha convertido en un \u201cmayor de edad\u201d capaz de dominar a la raz\u00f3n y ponerla a su servicio para un bienestar com\u00fan; por el contrario, la capacidad ut\u00f3pica se ha perdido pues ya no sue\u00f1a ni anhela, el hombre se ha vuelto un esclavo de la raz\u00f3n, del conocimiento y de la tecnolog\u00eda. El hombre ha vuelto a la raz\u00f3n un instrumento, y dicha raz\u00f3n instrumental se ha usado para destruir la misma humanidad. Bajo estas premisas el hombre se ha alejado de la naturaleza para convertirla en un objeto que debe ser dominado y como consecuencia de ello el objetivo respecto de la naturaleza, y la misma humanidad, es la dominaci\u00f3n (<em>Herrschaft<\/em>). La principal estrategia es presentar al sujeto como aquel que domina al objeto, por lo que es importante aqu\u00ed se\u00f1alar que todo acto de dominaci\u00f3n implica la objetivaci\u00f3n de lo que es dominado, tr\u00e1tese de la naturaleza u otro ser humano, en otras palabras: todo se puede volver un objeto material que puede ser cambiado, vendido, pose\u00eddo o desechado. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/c\/c3\/AdornoHorkheimerHabermasbyJeremyJShapiro2.png\/1024px-AdornoHorkheimerHabermasbyJeremyJShapiro2.png\" alt=\"\" \/><figcaption>Max Horkeimer y Theodor Adorno<\/figcaption><\/figure>\n\n\n\n<p>Las promesas incumplidas\nde la ilustraci\u00f3n duelen hoy m\u00e1s que nunca. Se nos vendi\u00f3 la idea de que el\nconocimiento y la raz\u00f3n nos dar\u00edan igualdad, libertad y fraternidad. Sin\nembargo, asistimos desde hace mucho al funeral de dicho ideal. El holocausto\nNazi es s\u00f3lo una muestra de c\u00f3mo la modernidad fue un fracaso y una farsa; pues\nla humanidad, que cre\u00eda haber superado la barbarie de los tiempos medievales,\ndescubri\u00f3 c\u00f3mo en pleno siglo XX el hombre \u201cracional\u201d fue capaz de cometer\nvej\u00e1menes impensables en sus cong\u00e9neres usando la raz\u00f3n y la tecnolog\u00eda para\nello. Esta imagen fue el detonante para cuestionar si realmente la ilustraci\u00f3n\nhab\u00eda sido una eficaz soluci\u00f3n o un mito sin sentido.<\/p>\n\n\n\n<p>El conocimiento libera nos prometieron. Es falso, as\u00ed, categ\u00f3rico. Hoy todos somos esclavos de la tecnolog\u00eda, hoy valoramos a las personas por su cercan\u00eda con \u201cla verdad\u201d. En pleno siglo XXI somos esclavos de estudios, rankings, revistas cient\u00edficas y luchas de poder en la ciencia. El hombre ha perdido su capacidad ut\u00f3pica pues ha dejado todo en manos de la rigurosa y fr\u00eda ciencia, ya no se puede so\u00f1ar, no se puede ser espiritual, no se puede pensar por fuera de aquello que nos dicen los hechos y los datos. La gran consecuencia: el hombre se somete al sistema, ese sistema que le dicta lo que debe ser, relegando lo que el hombre quiere ser. Se tiene que ser ingeniero, abogado, m\u00e9dico, cient\u00edfico; poco o nada importa querer ser (o ser) poeta, escritor, bailar\u00edn o artista en tanto eso no produce r\u00e9ditos econ\u00f3micos. Vemos entonces a la raz\u00f3n hecha instrumento, un instrumento para lograr dinero, poder y reconocimiento. En la educaci\u00f3n este panorama es horripilante, basta con hacerse una pregunta \u00bfcu\u00e1ntos de nosotros somos lo que de verdad quisimos ser y no lo que nos toc\u00f3 ser? As\u00ed las cosas la raz\u00f3n no libera, por el contrario, nos hace esclavos de un modelo que impone y nos vuelve meros instrumentos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.trotta.es\/static\/img\/portadas\/9788498796681_CPayxg9.png\" alt=\"\" \/><\/figure>\n\n\n\n<p>El conocimiento iguala\nnos prometieron. Falso tambi\u00e9n. Basta con analizar c\u00f3mo el conocimiento y la\nraz\u00f3n, al ser instrumentalizados y cosificados, se convierten en mercanc\u00eda.\nS\u00f3lo se puede acceder al conocimiento si se puede pagar. Para nadie es un\nsecreto que hay dos grandes divisiones en la sociedad: por un lado, aquellos\nque pueden pagar por el conocimiento y lo dominan, y por otro, aquellos\ncondenados a no poder educarse ni estar cerca de \u201cla raz\u00f3n\u201d. Existen as\u00ed dos\nclases claramente identificables: los que conocen y pueden pagar conocimiento,\ny los que no; los primeros dominan a los segundos. Asistimos, de nuevo, a la\nraz\u00f3n como instrumento de dominio, pero ahora tambi\u00e9n de segregaci\u00f3n. El hombre\nha sido capaz de dominar la naturaleza, de crear avances maravillosos en\nmedicina, por ejemplo, pero \u00bfqui\u00e9nes pueden acceder a ellos? De nuevo: s\u00f3lo\naquellos que puedan acceder al objeto por medio del dinero \u00bfes eso igualdad?\n\u00bfDe qu\u00e9 nos sirve lograr la foto de un agujero negro o encontrar la vacuna\ncontra alguna enfermedad si en la Guajira se mueren centenares de ni\u00f1os por\ndesnutrici\u00f3n? Es esa la idea de modernidad que debe ser cuestionada, aquella\nque olvida a la humanidad como fin y la vuelve un instrumento.<\/p>\n\n\n\n<p>El conocimiento nos har\u00e1 fraternos. Falso como todo lo anterior. Estamos en un mundo polarizado, donde los insultos, la violencia y el odio se esparcen por las redes sociales en forma de \u201c<em>fake news<\/em>\u201d. Todos queremos tener la raz\u00f3n pero nunca nos detenemos a escuchar al otro, nunca aceptamos que el otro puede tener la raz\u00f3n, nunca vemos al otro como una persona igual a nosotros, s\u00f3lo hay una raz\u00f3n dominante, lo dem\u00e1s son absurdas creencias que deben ser ridiculizadas y eliminadas; este es el origen de nuestra terrible tragedia. Todos queremos gritar para imponer nuestra \u201craz\u00f3n\u201d y aquel que no la comparta es nuestro enemigo \u00bfes esta la fraternidad que nos prometieron? De nuevo, la raz\u00f3n, \u201cnuestra raz\u00f3n\u201d es la forma de dominar a otro, de hacerlo menos, de maltratarlo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/f\/f7\/Chaplin_-_Modern_Times.jpg\/762px-Chaplin_-_Modern_Times.jpg\" alt=\"Resultado de imagen para razon instrumental\" \/><figcaption>Una bella met\u00e1fora de la Raz\u00f3n Instrumental en Chaplin<\/figcaption><\/figure>\n\n\n\n<p>Por eso les invit\u00f3 a que analicen la letra y el v\u00eddeo de una canci\u00f3n en particular: \u201cDo the Evolution\u201d de la banda Pearl Jam. En ella encontrar\u00e1n la m\u00e1s fiel descripci\u00f3n de lo que Adorno y Horkeimer anunciaron: La raz\u00f3n como forma de dominaci\u00f3n (basta con analizar en el v\u00eddeo a diferentes grupos y \u00e9pocas danzando junto al fuego \u2013iluminaci\u00f3n- mientras lo adoran como deidad), la tecnolog\u00eda como dominadora de la raz\u00f3n y la humanidad, el odio y el af\u00e1n de poder como constantes irremplazables de la humanidad, la tecnolog\u00eda como mercanc\u00eda al alcance de los que pueden pagarla.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/revistasoyrock.com.ar\/wp\/wp-content\/uploads\/2017\/04\/Pearl-Jam.jpg?fit=3928%2C2680&amp;ssl=1\" alt=\"Resultado de imagen para pearl jam\" \/><figcaption>Real Jam<\/figcaption><\/figure>\n\n\n\n<p>El v\u00eddeo es una muestra\nmuy interesante de la triste realidad que vivimos: una raz\u00f3n instrumental que\nevidencia las promesas incumplidas de la ilustraci\u00f3n. Hay que evolucionar como\nsea, al precio que sea, pero \u00bfevolucionar para qu\u00e9? \u00bfY c\u00f3mo qu\u00e9?<\/p>\n\n\n\n<p>En este link se puede encontrar el video:<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/aDaOgu2CQtI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las promesas incumplidas de la ilustraci\u00f3n duelen hoy m\u00e1s que nunca. Se nos vendi\u00f3 la idea de que el conocimiento y la raz\u00f3n nos dar\u00edan igualdad, libertad y fraternidad. Sin embargo, asistimos desde hace mucho al funeral de dicho ideal. El holocausto Nazi es s\u00f3lo una muestra de c\u00f3mo la modernidad fue un fracaso y una farsa; pues la humanidad, que cre\u00eda haber superado la barbarie de los tiempos medievales, descubri\u00f3 c\u00f3mo en pleno siglo XX el hombre \u201cracional\u201d fue capaz de cometer vej\u00e1menes impensables en sus cong\u00e9neres usando la raz\u00f3n y la tecnolog\u00eda para ello. Esta imagen fue el detonante para cuestionar si realmente la ilustraci\u00f3n hab\u00eda sido una eficaz soluci\u00f3n o un mito sin sentido.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/06\/05\/evoluciona-horkheimer-adorno-y-pearl-jam\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":24,"featured_media":92,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-91","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rock-y-sus-iconos","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/06\/f13f09d7b96173303f03ecc35228c547.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":1,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"predecessor-version":[{"id":93,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/91\/revisions\/93"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}