{"id":82,"date":"2019-05-07T15:59:23","date_gmt":"2019-05-07T15:59:23","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/rock-and-words\/?p=82"},"modified":"2019-05-07T16:36:02","modified_gmt":"2019-05-07T16:36:02","slug":"chernobil-panico-y-un-locutor-la-historia-tras-una-cancion-de-the-smiths","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/05\/07\/chernobil-panico-y-un-locutor-la-historia-tras-una-cancion-de-the-smiths\/","title":{"rendered":"Chern\u00f3bil, P\u00e1nico y un Locutor: La historia tras una canci\u00f3n de The Smiths"},"content":{"rendered":"\n<p>I<\/p>\n\n\n\n<p>El 26 de abril de 1986\nen la central nuclear <em>Vlad\u00edmir Ilich\nLenin <\/em>(m\u00e1s conocida como la central <em>Chern\u00f3bil<\/em>)\nocurri\u00f3 uno de los accidentes nucleares m\u00e1s catastr\u00f3ficos de la historia de la\nhumanidad. De acuerdo con la Escala Internacional de Accidentes Nucleares (<em>International Nuclear Event Scale<\/em>, INES)\nel evento alcanz\u00f3 una escala de 7 puntos (accidente grave), y junto con el\ndesastre de la central nuclear de <em>Fukushima<\/em>\nen Jap\u00f3n (marzo 11 de 2011), la tragedia de Chern\u00f3bil se constituy\u00f3 como uno de\nlos desastres medioambientales m\u00e1s devastadores, impactantes y recordados, a\ntal punto de convertirse en un icono de lo tr\u00e1gico en la d\u00e9cada de los 80 y la\ncultura popular; un acontecimiento estremecedor que inspir\u00f3 libros, series y\npel\u00edculas de todo tipo.<\/p>\n\n\n\n<p>Seg\u00fan se inform\u00f3, durante una prueba para simular un corte de suministro el\u00e9ctrico en la central nuclear, se present\u00f3 un s\u00fabito aumento de potencia en el reactor cuatro, esto produjo el sobrecalentamiento del n\u00facleo de \u00e9ste lo que termin\u00f3 provocando una explosi\u00f3n del hidr\u00f3geno acumulado en su interior. Como resultado de esta situaci\u00f3n, la cantidad de di\u00f3xido de uranio, carburo de boro, \u00f3xido de europio, erbio, aleaciones de circonio y grafito expulsados (todos materiales radiactivos o t\u00f3xicos) se estim\u00f3 en unas 500 veces mayor que la liberada por la bomba at\u00f3mica de <em>Hiroshima<\/em> en 1945. El resultado de esta explosi\u00f3n se tradujo en la muerte directa de 31 personas y la evacuaci\u00f3n de 116.000, lo que gener\u00f3 una alarma internacional al detectarse radiactividad en, al menos, 13 pa\u00edses de Europa central y oriental.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ichef.bbci.co.uk\/news\/976\/cpsprodpb\/E802\/production\/_105649395_a6bdf957-3ba3-4f6c-965a-7c5d7a0f13dd.jpg\" alt=\"Resultado de imagen para chernobyl\" \/><figcaption>Central Nuclear de Chern\u00f3bil (Ucrania)<\/figcaption><\/figure>\n\n\n\n<p>Despu\u00e9s del accidente\nse inici\u00f3 un proceso masivo de descontaminaci\u00f3n, contenci\u00f3n y mitigaci\u00f3n del\ndevastador impacto, en el proceso participaron aproximadamente 600.000 personas\ny dicho trabajo se realiz\u00f3 en las zonas circundantes al lugar del evento, para\nlo cual se aisl\u00f3 un \u00e1rea de 30 km de radio alrededor de la central nuclear -que\nsigue a\u00fan vigente-. Informes revelan tambi\u00e9n que cinco millones de personas\nvivieron en \u00e1reas contaminadas y 400.000 en \u00e1reas gravemente contaminadas, sin\nembargo, hasta hoy no existen trabajos concluyentes sobre el impacto real de\nesta tragedia.<\/p>\n\n\n\n<p>Como consecuencia de lo\nsucedido, por ejemplo, pinos en las cercan\u00edas del reactor (un \u00e1rea de cuatro\nkil\u00f3metros cuadrados) adquirieron un color marr\u00f3n dorado y murieron, adquiriendo\nas\u00ed el nombre de \u201cBosque Rojo\u201d. En un radio de unos 20 a 30 kil\u00f3metros\nalrededor del reactor se produjo un aumento de la mortalidad de plantas y\nanimales, as\u00ed como p\u00e9rdida en su capacidad reproductiva, sumado a esto, los\nalimentos de la zona fueron vetados en varias regiones de Europa, y el aumento\nde enfermedades como el c\u00e1ncer de tiroides aument\u00f3 (seg\u00fan la OMS\naproximadamente 4000 casos de relaci\u00f3n directa entre el accidente y la\nenfermedad fueron reportados). Como dato curioso se tiene que en los a\u00f1os\nposteriores al desastre, en la zona de exclusi\u00f3n, que fue abandonada por el ser\nhumano, ha florecido la vida salvaje y varias especies de animales salvajes y\naves que no se hab\u00edan visto en la zona antes del desastre, se encuentran ahora\nen abundancia gracias a la ausencia del hombre.<\/p>\n\n\n\n<p>El Gobierno de Ucrania (donde actualmente se encuentra la central) negoci\u00f3 con la comunidad internacional el cierre definitivo de <em>Chern\u00f3bil<\/em>, dicho cierre se complet\u00f3 el 15 de diciembre del 2000. Inmediatamente despu\u00e9s del accidente se construy\u00f3 un \u201csarc\u00f3fago\u201d para aislar el reactor cuatro, pero diversos fen\u00f3menos naturales y el paso del tiempo hicieron que se deteriorara hasta el punto de estar en riesgo de colapso, por ello en el 2004 se inici\u00f3 la construcci\u00f3n de un nuevo sarc\u00f3fago para el reactor, el resto de reactores de la central est\u00e1n inactivos. En noviembre de 2016, treinta a\u00f1os despu\u00e9s de la tragedia, se inaugur\u00f3 un nuevo \u201csarc\u00f3fago seguro\u201d, toda una mega estructura m\u00f3vil, la mayor construida hasta la fecha en el mundo; tiene forma de arco, posee 110 metros de alto, 150 de ancho y 256 de largo y pesa m\u00e1s de 30.000 toneladas. Se construy\u00f3 a 180 metros del reactor y luego se ubic\u00f3 sobre \u00e9l mediante un sofisticado sistema de rieles y se estima que tendr\u00e1 una duraci\u00f3n de m\u00e1s de cien a\u00f1os. Se espera as\u00ed sepultar el horror de Chern\u00f3bil.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.clarin.com\/2011\/04\/18\/BJN6TbW9Vx_1256x620.jpg\" alt=\"Resultado de imagen para chernobyl\" \/><figcaption>Chern\u00f3bil 30 a\u00f1os despu\u00e9s<\/figcaption><\/figure>\n\n\n\n<p>II<\/p>\n\n\n\n<p><em>Stephen Richard Wright<\/em>, m\u00e1s conocido como <em>Steve Wright<\/em> naci\u00f3 el 26 de agosto de 1954 en Londres y tiene fama como Disc Jockey (DJ) o \u201cPinchadiscos\u201d de la BBC. Su estilo particular lo llev\u00f3 a crear el conocido programa <em>The Morning Zoo<\/em>, un concepto inspirado en una reuni\u00f3n miscel\u00e1nea de g\u00e9neros y entrevistas que suele conocerse tambi\u00e9n como el Top 40, o en nuestro medio, \u201cLas 40 principales\u201d. Se trata de un formato zool\u00f3gico (<em>zoo format<\/em>) en donde, por lo general, dos o tres personalidades radiales hablan de manera c\u00f3mica y espont\u00e1nea sobre temas de actualidad; sumado a esto tambi\u00e9n suele ofrecer llamadas guiadas al p\u00fablico y concursos entre los oyentes. <em>Wright<\/em> tambi\u00e9n ha incursionado en la TV presentando programas como \u201c<em>Home Truths<\/em>\u201d, \u201c<em>The Steve Wright People Show<\/em>\u201d y \u201c<em>Top of the Pops<\/em>\u201d entre otros y es considerado una leyenda de los medios brit\u00e1nicos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i.dailymail.co.uk\/i\/pix\/2015\/12\/03\/01\/2F01140D00000578-3343612-Throwback_The_much_loved_radio_personality_has_been_in_the_natio-a-3_1449105868020.jpg\" alt=\"Resultado de imagen para steven wright young bbc\" \/><figcaption>Wright en los 80<\/figcaption><\/figure>\n\n\n\n<p>Proveniente de una cl\u00e1sica familia de estirpe trabajadora, <em>Wright<\/em> desde ni\u00f1o tuvo la ambici\u00f3n de trabajar en el mundo del entretenimiento, por lo que desde sus primeros a\u00f1os se enrol\u00f3 en la presentaci\u00f3n radial (primero en la escuela y luego en programas locales). Su gran oportunidad se dio cuando se vincul\u00f3 con <em>Radio Luxenbourg<\/em> presentando su propio show nocturno. Pero fue en 1981 cuando Steve revolucion\u00f3 la radio brit\u00e1nica con la introducci\u00f3n del formato zool\u00f3gico en la Radio 1 de la BBC. La creaci\u00f3n de personajes que realizaban bromas por tel\u00e9fonos (creados y representados por <em>Gavin McCoy<\/em>, <em>Peter Dickson<\/em>, <em>Richard Easter<\/em> y <em>Phil Cornwell<\/em>) y un estilo que privilegiaba la irreverencia sobre la sensibilidad y lo racional, lo llevaron pronto a ser un locutor y DJ reconocido en todo el Reino Unido. La evoluci\u00f3n de su formato lo llev\u00f3 con los a\u00f1os a crear personajes ficticios, burlarse de noticias extra\u00f1as o curiosas, y a realizar bocetos de situaciones c\u00f3micas que eran transmitidas en sus shows. Actualmente trabaja para la BBC 2 y los detalles de su vida personal son pocos. <em>Wright<\/em> tiene una audiencia promedio diaria de m\u00e1s de 8 millones de radioescuchas. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ichef.bbci.co.uk\/images\/ic\/480xn\/p057tcc4.jpg\" alt=\"Resultado de imagen para steven wright bbc\" \/><figcaption>Wright en la actualidad para BBC Radio 2<\/figcaption><\/figure>\n\n\n\n<p>En Colombia es com\u00fan\nescuchar emisoras que siguen el formato que perfeccion\u00f3 <em>Wright<\/em> en los ochenta, y desde luego es com\u00fan tambi\u00e9n encontrar\nentusiastas seguidores de \u00e9stas. Este tipo de programas poco a poco ha ido ganando\nterreno en las emisoras locales y nacionales, y &nbsp;las diferencias se observan en la medida en\nque se escuche un programa originado desde ciudades grandes como Bogot\u00e1,\nMedell\u00edn o Cali a uno generado desde \u201cprovincia\u201d. Pero el factor com\u00fan que\nmarca a estos programas es la actitud irreverente y burlona de los\npresentadores hacia los invitados y los radio oyentes, que se traduce en chistes\nde doble sentido y bullying (los norteamericanos lo llamar\u00edan \u201c<em>roast<\/em>\u201d) hacia personajes de la vida\nnacional, principalmente far\u00e1ndula y pol\u00edtica. El formato tambi\u00e9n incluye la\ncreaci\u00f3n de personajes ficticios como caricaturas regionales: el negro del\npac\u00edfico, el santandereano agresivo, el bogotano \u201cgomelo\u201d, el antioque\u00f1o \u201ctraqueto\u201d\no el pastuso ingenuo. En cuanto a la m\u00fasica, poco o nada se aporta excepto\ncanciones populares y de moda.<\/p>\n\n\n\n<p>Personalmente, mi encuentro con este tipo de programas y formato ocurre cuando abordo un taxi, de los amarillos, en las ma\u00f1anas. Locutores que gritan, personajes que entran sin orden ni guion alguno, reacciones espont\u00e1neas a situaciones espont\u00e1neas, chistes con doble sentido (generalmente de contenido sexual o machista\/feminista) dominan la radio. El escenario se eleva a una potencia mayor cuando es navidad y fin de a\u00f1o pues se tiene material suficiente para hacer bullying a los personajes que han servido como comidilla para los medios durante toda la temporada. Voces afeminadas, campesinos con una \u201csabidur\u00eda popular\u201d bizarra, pol\u00edticos descarados, locutores inquisitivos y oyentes entusiasmados y dispuestos a ser puestos en el pared\u00f3n de las burlas se mezclan para crear un verdadero zool\u00f3gico auditivo, en mi caso, apenas tolerable, pero que divierte a los conductores de una manera asombrosa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/SQHH5Ae8BJU\/hqdefault.jpg\" alt=\"Resultado de imagen para las 40 principales colombia\" \/><figcaption>Las 40 principales, Colombia<\/figcaption><\/figure>\n\n\n\n<p>Si algo me llama la\natenci\u00f3n de este tipo de programas y personajes, m\u00e1s all\u00e1 de cuestionar si su\nestilo es est\u00e9tico o adecuado (cada quien determina qu\u00e9 escucha y por qu\u00e9 lo\nhace), es su enorme capacidad para abstraer de la realidad nacional al oyente y\ndeformarla a tal punto de generar en \u00e9l una c\u00f3moda par\u00e1lisis (para recordar a\nPink Floyd). Cuando un seguidor de estos <em>shows<\/em>\nest\u00e1 pegado a su contenido se anula cualquier ejercicio de racionalidad o\nrazonabilidad, lo \u201cpol\u00edticamente correcto\u201d no existe y lo que en otros\nescenarios ser\u00eda deleznable o censurable all\u00ed es objeto de culto sin reproche\nalguno, como una religi\u00f3n. Lo grotesco, para muchos, es oro para estos\nprogramas y lo obsceno es el n\u00e9ctar del que escucha. En este caso asistimos a\nla anulaci\u00f3n de cualquier ejercicio de \u00e9tica o moralidad respecto de las vidas\ny tragedias ajenas, nos encontramos ante el escenario de libertad absoluta\nrespecto de la empat\u00eda o antipat\u00eda respecto de los otros. Los DJ o \u201cPinchadiscos\u201d\ndirigen as\u00ed las emociones de los radioescuchas sin l\u00edmite alguno, una verdadera\nobra de t\u00edteres a trav\u00e9s de un zool\u00f3gico ca\u00f3tico.<\/p>\n\n\n\n<p>III<\/p>\n\n\n\n<p>El P\u00e1nico se dispers\u00f3 por <em>Chern\u00f3bil<\/em> en 1986, los ecos de la ocurrencia de la terrible tragedia se expand\u00edan tan r\u00e1pido como los mismos efectos radioactivos. Por aquellos d\u00edas <em>Steve Wright<\/em> &nbsp;trabajaba para la radio 1 de la BBC y, como todos los dem\u00e1s medios, inform\u00f3 sobre el lamentable evento en la central nuclear. Tan pronto ley\u00f3 la noticia, Steve solt\u00f3 \u201c<em>I\u2019m your man<\/em>\u201d de <em>Wham!<\/em> (el famoso d\u00fao compuesto por <em>George Michael<\/em> y <em>Andrew Ridgeley<\/em>). Esta situaci\u00f3n no agrad\u00f3 mucho a los oyentes, quienes pensaron que tal acto supon\u00eda una falta de respeto y sensibilidad por parte de <em>Wright<\/em> hacia las v\u00edctimas de la tragedia nuclear y hacia los oyentes en general. Algunos de esos oyentes eran &nbsp;<em>Steven Patrick Morrissey<\/em> y <em>John Martin Maher<\/em> (<em>Johnny Marr<\/em>) l\u00edder y guitarrista de <em>The Smiths<\/em>. Seguramente <em>Morrissey<\/em> y <em>Marr<\/em> pensaron que no hab\u00eda relaci\u00f3n entre la tragedia de Chern\u00f3bil y \u201c<em>I\u00b4m your man<\/em>\u201d de <em>Wham<\/em>! \u00bfQu\u00e9 tiene que ver esto con la vida de la gente o con sus vidas? Era inconcebible que despu\u00e9s de escuchar la catastr\u00f3fica noticia tan s\u00f3lo se pensara en bailar al ritmo del pop de la \u00e9poca para as\u00ed olvidar el desastre. &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.mor.bo\/wp-content\/uploads\/2016\/10\/johnny-marr-y-morrissey.jpg\" alt=\"Resultado de imagen para morrissey and marr\" \/><figcaption>Morrissey y Marr<\/figcaption><\/figure>\n\n\n\n<p>Como resultado de este\nepisodio, y como respuesta a la insensibilidad de <em>Wright<\/em>, <em>The Smiths<\/em>\ndecidieron componer una canci\u00f3n: \u201c<em>Panic<\/em>\u201d\n(una de mis canciones favoritas de todos los tiempos; y admito que uno de mis\nplaceres m\u00e1s recurrentes es conducir mi autom\u00f3vil con <em>Panic<\/em> a todo volumen). La canci\u00f3n es corta en duraci\u00f3n, pero tiene\nun ritmo y una atm\u00f3sfera \u00fanica, la voz de Morrissey es el complemento ideal\npara una composici\u00f3n ic\u00f3nica que evoca el ambiente <em>glam<\/em> setentero presente en \u201c<em>Metal\nGur\u00fa<\/em>\u201d de <em>T-Rex<\/em> pero con una\nversi\u00f3n propia de los tard\u00edos ochenta.<\/p>\n\n\n\n<p>Lo que m\u00e1s llam\u00f3 la\natenci\u00f3n de <em>Panic<\/em> fue su letra,\ntildada por muchos de racista: \u201c<em>Burn down\nthe disco. Hang the blessed DJ because the music that they constantly play, it\nsays nothing to me about my life<\/em>\u201d (Quemen la discoteca. Cuelguen al bendito\nDJ. Porque la m\u00fasica que constantemente coloca no dice nada sobre mi vida). Pero\npese a que <em>Morrissey<\/em> deseaba dar su\npunto de vista acerca de la actitud insensible de <em>Wright<\/em> su intento no sali\u00f3 del todo bien, por el contrario, su\ncanci\u00f3n fue tomada como una clara de muestra de odio y racismo, se hablaba de una\ncanci\u00f3n y una banda que incitaba a quemar la m\u00fasica negra.<\/p>\n\n\n\n<p>Cuando <em>Morrissey<\/em> fue cuestionado sobre este episodio, su respuesta no fue de mucha ayuda, y lejos de apagar el fuego agreg\u00f3 m\u00e1s combustible, en una entrevista realizada por <em>Frank Owen<\/em> para la revista \u201c<em>Melody Maker<\/em>\u201d se despach\u00f3 as\u00ed: \u201c<em>El reggae, por ejemplo, para m\u00ed es la m\u00fasica m\u00e1s racista de todo el mundo. Es una absoluta glorificaci\u00f3n de la supremac\u00eda negra <\/em>[\u2026]<em> Hay una l\u00ednea, cuando la defensa de una raza se convierte en un ataque para la otra raza y, como consecuencia de la historia de los negros y la opresi\u00f3n, nos damos cuenta de que tiene que haber una defensa muy fuerte. Pero creo que a veces es muy extrema<\/em>.\u201d Y como si esto no fuese poco, agreg\u00f3: \u201c<em>Odio a Stevie Wonder. Creo que Diana Ross es horrorosa. Odio todos esos discos de los 40 Principales: Janet Jackson, Whitney Houston\u2026 Creo que son repugnantes al extremo<\/em>\u201d. Finalmente, s\u00ed, hay m\u00e1s, al expresar su opini\u00f3n sobre la m\u00fasica negra, <em>Morrissey<\/em> recit\u00f3 uno de los versos de <em>Panic<\/em>: \u201c<em>En esencia, esta m\u00fasica no me dice nada en absoluto<\/em>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/NVdCv_1PeDY\/maxresdefault.jpg\" alt=\"Resultado de imagen para panic the smiths\" \/><figcaption>Morrissey y la letra de Panic<\/figcaption><\/figure>\n\n\n\n<p>En el fondo lo que <em>Morrissey<\/em> parec\u00eda intentar decir era su cr\u00edtica a un modelo que buscaba, a su juicio, dejar por fuera de las listas al <em>indie <\/em>blanco a trav\u00e9s de emisoras ca\u00f3ticas, superficiales y vendidas. La cr\u00edtica que <em>Panic<\/em> verdaderamente transmit\u00eda era la de un sistema acomodado para privilegiar la moda y el sinsentido sobre lo que realmente afecta la vida de las personas; en la misma entrevista dijo: \u201c<em>Las listas han sido creadas claramente como una forma absoluta de escapismo m\u00e1s, no como algo por lo que alguien pueda ganar reconocimiento. Lo encuentro muy descorazonador porque no siempre ha sido as\u00ed. \u00bfNo es curioso que pr\u00e1cticamente ninguno de estos discos refleje la vida como la vivimos? \u00bfNo es curioso que el 93,5 por ciento de estos discos refleje la vida como no es? Eso me deja perplejo<\/em>.\u201d <\/p>\n\n\n\n<p>  <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/wMykYSQaG_c\/maxresdefault.jpg\" alt=\"Resultado de imagen para panic the smiths\" \/><figcaption> <br><a href=\"https:\/\/www.youtube.com\/watch?v=wMykYSQaG_c\">https:\/\/www.youtube.com\/watch?v=wMykYSQaG_c<\/a>  <\/figcaption><\/figure>\n\n\n\n<p><br><a href=\"https:\/\/www.youtube.com\/watch?v=wMykYSQaG_c\">h<\/a><\/p>\n\n\n\n<p><em>Panic<\/em> fue publicada como single en 1986, pero nunca se incluy\u00f3 en un trabajo oficial, aunque s\u00ed apareci\u00f3 en el \u00e1lbum recopilatorio \u201c<em>Louder than bombs<\/em>\u201d de 1987. La portada del sencillo era una fotograf\u00eda del actor <em>Richard Bradford<\/em>. La presentaci\u00f3n en vivo de <em>Panic<\/em> inclu\u00eda a Morrissey balance\u00e1ndose una soga sobre el escenario mientras repet\u00eda el estribillo: \u201c<em>Hang de DJ<\/em>\u201d y para completar el show usaba una camiseta con una fotograf\u00eda del <em>Steve Wright<\/em> que dec\u00eda tambi\u00e9n \u201c<em>Hang de DJ<\/em>\u201d (ahorquen al locutor). <em>The Smiths <\/em>al final consiguieron que su canci\u00f3n sonara en Radio 1 de la BBC y el mismo <em>Steve Wright<\/em> puso el tema en varias ocasiones, sin saber su acto hab\u00eda generado esta tremenda pieza musical.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/en\/thumb\/a\/a5\/Panic_The_Smiths.jpg\/220px-Panic_The_Smiths.jpg\" alt=\"Resultado de imagen para panic the smiths\" \/><figcaption>Portada de Panic (sencillo)<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Panic fue publicada como single en 1986, pero nunca se incluy\u00f3 en un trabajo oficial, aunque s\u00ed apareci\u00f3 en el \u00e1lbum recopilatorio \u201cLouder than bombs\u201d de 1987. La portada del sencillo era una fotograf\u00eda del actor Richard Bradford. La presentaci\u00f3n en vivo de Panic inclu\u00eda a Morrissey balance\u00e1ndose una soga sobre el escenario mientras repet\u00eda el estribillo: \u201cHang de DJ\u201d y para completar el show usaba una camiseta con una fotograf\u00eda del Steve Wright que dec\u00eda tambi\u00e9n \u201cHang de DJ\u201d (ahorquen al locutor). The Smiths al final consiguieron que su canci\u00f3n sonara en Radio 1 de la BBC y el mismo Steve Wright puso el tema en varias ocasiones, sin saber su acto hab\u00eda generado esta tremenda pieza musical.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/05\/07\/chernobil-panico-y-un-locutor-la-historia-tras-una-cancion-de-the-smiths\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":24,"featured_media":83,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-82","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rock-y-sus-iconos","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/05\/174738_70916df21.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":4,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":87,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/82\/revisions\/87"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media\/83"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}