{"id":63,"date":"2019-04-23T14:30:48","date_gmt":"2019-04-23T14:30:48","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/rock-and-words\/?p=63"},"modified":"2019-04-23T15:00:08","modified_gmt":"2019-04-23T15:00:08","slug":"un-homenaje-a-siena-y-sus-colores-desde-el-rock-roll","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/04\/23\/un-homenaje-a-siena-y-sus-colores-desde-el-rock-roll\/","title":{"rendered":"Un homenaje a Siena y sus colores desde el Rock &amp; Roll"},"content":{"rendered":"\n<p>Dedicado a\nmi amigo y notable anfitri\u00f3n: Massimiliano Montini<\/p>\n\n\n\n<p>I<\/p>\n\n\n\n<p>Tuve la\noportunidad de conocer la encantadora ciudad de Siena hace poco, esto gracias a\nlas bondades de mi trabajo como docente y acad\u00e9mico. Primero debo confesar que\nsiempre que fantaseaba acerca de c\u00f3mo ser\u00eda la Toscana italiana mis im\u00e1genes se\nremit\u00edan a la obra f\u00edlmica de <em>Pier Paolo\nPasolini<\/em>, puntualmente en su representaci\u00f3n del Decamer\u00f3n de <em>Boccaccio<\/em>, y creaba en mi mente una\ntierra llena de colores y arabescos donde los tonos ocre terrosos y oscuros\npredominaban, en casas ape\u00f1uscadas de forma asim\u00e9trica y con laberintos por\ncalles. Pensaba tambi\u00e9n en la Siena de <em>Federigo\nTozzi<\/em> (1883-1920) y su idea de que el estado de \u00e1nimo es fundamental para\ncomprender una ciudad (lo mismo podr\u00eda decirse para una canci\u00f3n, un artista o\nuna banda), de este modo las ciudades se pueden \u201cleer\u201d y cada lectura depender\u00e1\nde nuestras emociones y prejuicios. Recordaba tambi\u00e9n que <em>Tozzi<\/em> en sus obras ilustraba una postura realista en la que muestra\nc\u00f3mo el ser humano es incapaz de adaptarse a la realidad, lo que desencadena\nfinalmente una sensaci\u00f3n de ineptitud y una profunda insatisfacci\u00f3n con lo que\nse es; se trata de un signo de la fatalidad contempor\u00e1nea que <em>Hesse<\/em> supo expresar de manera magn\u00edfica\nen su Lobo Estepario. La obra del italiano es un ejemplo de la exaltaci\u00f3n de la\nrealidad, en ocasiones psicod\u00e9lica, que conlleva a una reflexi\u00f3n sobre lo\ninsignificante&nbsp; que es el ser humano\nfrente al mundo y la historia a la que se enfrenta; as\u00ed las cosas, lo \u00fanico que\nqueda es tratar de comprender el limitado espacio donde se vive, anulando as\u00ed\ncualquier pretensi\u00f3n de universalidad emancipadora. Asistimos entonces a la\nobra de <em>Tozzi<\/em> en la que se presenta\nun ser humano parroquial, entendible s\u00f3lo desde su espacio de desarrollo, por\ntal motivo <em>Tozzi<\/em> siempre profundiz\u00f3\nen su h\u00e1bitat: Siena (Roma, en su obra \u201cLos Ego\u00edstas\u201d). Todos tenemos nuestra \u201cBucaramanga\u201d\ncomo resultado de una construcci\u00f3n individual marcada por las experiencias y anhelos\nla ciudad nos ha dado, somos lo que somos desde nuestra Bucaramanga (o\ncualquier otra ciudad), as\u00ed, Tozzi escribe en \u201cCon los ojos cerrados\u201d (1913):<\/p>\n\n\n\n<p>\u201c<em>Estaba d\u00edas enteros, s\u00f3lo; en casa; mirando con la cara contra los vidrios, el sutil rectangular azul entre los techados. Aquel azul tonto, as\u00ed lejano, le daba c\u00f3lera. [&#8230;] Y entonces sent\u00eda el vac\u00edo de aquella soledad recluida en uno de los m\u00e1s antiguos palacios de Siena, totalmente deshabitado, con la torre trunca sobre el t\u00e9trico Arco de los Rossi; en medio de las casas obscuras e inertes, una apretada a la otra, con blasones esculpidos que nadie conoc\u00eda m\u00e1s, de familias desaparecidas.<\/em>\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/msur.es\/wp-content\/uploads\/2013\/08\/tozzi.jpg\" alt=\"Resultado de imagen para federigo tozzi\" \/><figcaption>Federigo Tozzi<\/figcaption><\/figure>\n\n\n\n<p>Esta es\nla Siena de Tozzi, o mejor, esta es la lectura de Siena de Tozzi. Quer\u00eda\ncomprobar entonces si estas im\u00e1genes que habitaban mi mente coincid\u00edan con mi\nexperiencia en Siena, experiencia que se prolongar\u00eda por tres semanas como\nProfesor invitado de hermen\u00e9utica del derecho a la Facultad de Jurisprudencia\nde la Universidad de Siena.<\/p>\n\n\n\n<p>II<\/p>\n\n\n\n<p>Llegu\u00e9 a\nSiena un martes en la ma\u00f1ana, despu\u00e9s de tomar un bus en Florencia que tard\u00f3\npoco m\u00e1s de una hora. A\u00fan la primavera no hab\u00eda llegado del todo a esta regi\u00f3n,\npor lo que el fr\u00edo dominaba el ambiente pese a que exist\u00edan momentos del d\u00eda\ncon un sol brillante y una claridad en el cielo asombrosa. A medida que me\nacercaba a Siena se pod\u00eda ver su imponente estructura: su Domo, la Torre de\nMangia y la Bas\u00edlica de San Dom\u00e9nico, y una vez descend\u00ed del bus se present\u00f3\nante m\u00ed una ciudad peque\u00f1a pero imponente. Part\u00ed de una plaza que me adentr\u00f3 en\ninnumerables calles angostas y confusas de lozas gastadas, grises y fr\u00edas,\ncalles llenas de arcos llamativos, de fachadas vencidas por el tiempo pero a\u00fan\nde pie y con cicatrices artesanales para reparar su deterioro, innumerables\niglesias e im\u00e1genes en los muros, im\u00e1genes que llamaron mi atenci\u00f3n, im\u00e1genes\nque anunciaban rivalidades, divisiones e historia; pese a todo no hab\u00eda calidez\na\u00fan en esos parajes. Ten\u00eda la sensaci\u00f3n de caminar por una ciudad hosca y\n\u00e1spera, indolente ante sus habitantes. <\/p>\n\n\n\n<p>A medida que pasaban los d\u00edas me fui perdiendo en la historia, los colores y las emociones de Siena. De esa imagen inicial, de esa primera lectura (para recordar a <em>Tozzi<\/em>) marcada por la indolencia de una ciudad vetusta y sin nada m\u00e1s que ofrecer que laberintos angostos, pas\u00e9 a una relaci\u00f3n de indagaci\u00f3n que me llev\u00f3 a entender las ra\u00edces sienesas y su encanto. Cada calle recorrida era un paseo por las rivalidades del Palio: la legendaria y centenaria competencia de caballos, la m\u00e1s extraordinaria del mundo, donde las 17 contradas (barrios) de Siena se juegan su honor e historia cada a\u00f1o en Julio 2 (en honor a la Virgen de Provenzano) y Agosto 16 (en honor a la Virgen de la Asunci\u00f3n). De las 17 contradas s\u00f3lo 10 participan en la carrera, esas 10 se eligen por sorteo, as\u00ed, el a\u00f1o que sigue corren las 7 restantes que no salieron favorecidas y tres m\u00e1s (de nuevo, por sorteo elegidas). Para entender esta ancestral y maravillosa tradici\u00f3n hay que leer en clave de sacralidad y pasi\u00f3n la simbolog\u00eda de pertenecer a una contrada, cada una de ellas representada por seres u objetos emblem\u00e1ticos: una oca, un unicornio, un puercoesp\u00edn, un carnero, una concha o una torre sobre un elefante, entre otros. Cada miembro de una contrada lo es desde su nacimiento y sigue la l\u00ednea de su familia, en ocasiones la rivalidad es tan grande que, como en Romeo y Julieta de <em>Shakespeare<\/em>, es imposible que dos miembros de contradas rivales se relacionen entre s\u00ed. Al final del imponente y tenso Palio, la barriada ganadora celebra toda la noche, su caballo es paseado y llevado a la Iglesia de la contrada para ser ovacionado en un frenes\u00ed inolvidable. Fue aqu\u00ed donde descubr\u00ed los colores y la verdadera pasi\u00f3n de Siena, y aquella ciudad incipiente al inicio, se volvi\u00f3 hacia m\u00ed con una cantidad variopinta de s\u00edmbolos, colores, historias, an\u00e9cdotas, sabores y recuerdos. Siena es una ciudad que se abre a qui\u00e9n quiere conocer su historia desde la pasi\u00f3n local, desde lo parroquial, desde aquello que la hace \u00fanica frente a la universalidad que no admite comparaci\u00f3n. Hay que vivir Siena en clave de contrada. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"442\" src=\"http:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image.png\" alt=\"\" class=\"wp-image-66\" srcset=\"https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image.png 700w, https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image-300x189.png 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption>El espectacular Palio en la Plaza del Campo<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>A medida que recorr\u00eda las calles y me adentraba en las contradas (por donde estaba ubicado el hotel donde me acomod\u00e9, decid\u00ed que \u201cmi contrada\u201d ser\u00eda Valdimontone -el carnero- cuyos colores son el blanco, amarillo y rojo) los colores y las im\u00e1genes me recordaban a <em>Pasolini<\/em> y su cinta, me recordaban a <em>Tozzi<\/em> y su visi\u00f3n de la realidad parroquial. Siena ahora era inagotable, se ofrec\u00eda de forma infinita a m\u00ed; la mezquindad qued\u00f3 atr\u00e1s y el temor de no poder absorber todo el universo sien\u00e9s me asechaba. Cada esquina, cada fuente, cada imagen me llenaba de colores, historias, jerarqu\u00edas y datos. Pens\u00e9 entonces que es incre\u00edble c\u00f3mo una ciudad tan peque\u00f1a fuese tan profunda y compleja. Al final entend\u00ed que la clave est\u00e1 en los colores, Siena los tiene todos: el azul del mar que resalta en la contrada de la Onda, el rojo y amarillo intenso de la contrada Valdimontone (Valle del carnero), el elegante negro y rojo de la contrada Civeta (lechuza), y as\u00ed. Todos los miembros de las contradas viven de sus colores, viven de su espacio en la ciudad, de sus rivales y amigos, Siena es una mezcla y lucha de colores, pero un color predomina: el ocre del Tufo, el color de la tierra con que se cubre la pista en la que se corre el Palio, sobre el tufo se construye Siena. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"300\" src=\"http:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image-1.png\" alt=\"\" class=\"wp-image-67\" srcset=\"https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image-1.png 500w, https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/image-1-300x180.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption>Las contradas de Siena<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>III<\/p>\n\n\n\n<p>En el\n2017 tambi\u00e9n tuve la fortuna de conocer Suecia, permanec\u00ed poco m\u00e1s de una\nsemana en Uppsala y Estocolmo asistiendo como invitado a un seminario sobre\nfilosof\u00eda en la Universidad de Uppsala. Debo decir que los colores de esta\nparte del mundo no son tan vibrantes como los de Siena, pero ello no implica\nque los parajes escandinavos carezcan de encanto y belleza, simplemente son\ntonos distintos, para un estado de \u00e1nimo distinto. Para m\u00ed, Uppsala, citando a <em>Taylor Cole<\/em>rdige (y a Iron Maiden), era\ncomo un \u201c<em>barco pintado en un oc\u00e9ano\npintado<\/em>\u201d, era azul, azul est\u00e1tico. Pero pese a mi impresi\u00f3n de Suecia, o al\nmenos de una parte de ella, record\u00e9 a Siena (a\u00fan sin conocerla) estando en\nUppsala, me refiero a que lejos de pensar en ABBA (que confieso es una de mis\nbandas favoritas de todos los tiempos), pens\u00e9 en Siena Root, una muy buena\nbanda de Rock, que recomiendo escuchen sin reservas.<\/p>\n\n\n\n<p>Siena\nRoot es una agrupaci\u00f3n con un espectro musical variado y colorido que cobr\u00f3\nvida en Estocolmo a finales de los a\u00f1os 90 y hoy es considerada una de las\nbandas suecas pioneras en la m\u00fasica rock de la vieja escuela. Su m\u00fasica tiene\nun aire al blues que transita al rock cl\u00e1sico con canciones como \u201cRasayana\u201d, \u201cGood\nand Bad\u201d, \u201cBetween the lines\u201d o \u201cWe are them\u201d. <\/p>\n\n\n\n<p><br>\n<br>\nSiena Root se caracteriza por sus presentaciones en vivo, llenas de color,\nteatralidad y sorpresas. Una apuesta por la pasi\u00f3n y la energ\u00eda que rara vez se\nesperar\u00eda de una banda sueca distinta del Black Metal. La banda es un claro\nejemplo del Rock and Roll cl\u00e1sico sin mayores pretensiones que emocionar los\nsentidos.<\/p>\n\n\n\n<p>El nombre de la banda, seg\u00fan sus integrantes, se debe a los colores de Siena, esos mismos que a m\u00ed me fascinaron, y que inspiraron a unos rockeros suecos que vieron en esta ciudad italiana la ra\u00edz de su m\u00fasica \u00bfpor qu\u00e9 la ra\u00edz de Siena? Quiz\u00e1s porque el blues es azul, el hard rock es negro y el reggae es de color panafricano, esta mezcla son los colores de Siena y el Palio, todo esto bajo un color c\u00e1lido, originario de las ra\u00edces fangosas de la tierra como el tufo. Debido a que este sonido tiene ra\u00edces profundas, tambi\u00e9n era natural dejar que la ra\u00edz formara parte del nombre de la banda. As\u00ed como en cada Palio hay una mezcla fren\u00e9tica de colores y pasiones, en cada tema de Siena Root hay una escala de sensaciones tan puras que es imposible no asociar su m\u00fasica con la esencia del Rock: las emociones m\u00e1s puras de cada persona.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.heavypsychsounds.com\/file\/bands\/siena-root\/photos\/SienaRoot_th.jpg\" alt=\"Resultado de imagen para siena root live\" \/><figcaption>Siena Root<\/figcaption><\/figure>\n\n\n\n<p>Este es\nmi homenaje a una ciudad que me maravill\u00f3 y a una banda que tambi\u00e9n fue\natrapada por la magia sienesa. Siena es un estado de \u00e1nimo, es una canci\u00f3n, es\nun himno del Rock and Roll bien hecho accesible s\u00f3lo para aquellos que deseen\nperderse en la pasi\u00f3n de la historia y la cotidianidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este es mi homenaje a una ciudad que me maravill\u00f3 y a una banda que tambi\u00e9n fue atrapada por la magia sienesa. Siena es un estado de \u00e1nimo, es una canci\u00f3n, es un himno del Rock and Roll bien hecho accesible s\u00f3lo para aquellos que deseen perderse en la pasi\u00f3n de la historia y la cotidianidad.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/rock-and-words\/2019\/04\/23\/un-homenaje-a-siena-y-sus-colores-desde-el-rock-roll\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":24,"featured_media":64,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-63","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rock-y-sus-iconos","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/rock-and-words\/files\/2019\/04\/siena-root.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":3,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/63\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/posts\/63\/revisions\/69"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media\/64"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/media?parent=63"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/categories?post=63"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/rock-and-words\/wp-json\/wp\/v2\/tags?post=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}