{"id":239,"date":"2012-05-21T00:09:51","date_gmt":"2012-05-21T05:09:51","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/paisaje-urbano\/?p=239"},"modified":"2012-05-21T00:09:51","modified_gmt":"2012-05-21T05:09:51","slug":"llegaron-los-barbaros-2","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/sin-categoria\/239-llegaron-los-barbaros-2","title":{"rendered":"llegaron los Barbaros&#8230;&#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.vanguardia.com\/paisaje-urbano\/files\/2012\/05\/misdocumentos-111.jpg\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-240\" src=\"http:\/\/blogs.vanguardia.com\/paisaje-urbano\/files\/2012\/05\/misdocumentos-111-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/files\/2012\/05\/misdocumentos-111-300x225.jpg 300w, https:\/\/blogs.vanguardia.com\/paisaje-urbano\/files\/2012\/05\/misdocumentos-111-1024x768.jpg 1024w, https:\/\/blogs.vanguardia.com\/paisaje-urbano\/files\/2012\/05\/misdocumentos-111.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Noooo \u00a0es la cuadrilla de mantenimiento de la corporaci\u00f3n de defensa de la meseta de Bucaramanga.<\/p>\n<p>El parque\u00a0 mirador del oriente por su posici\u00f3n geogr\u00e1fica en los l\u00edmites de la periferia urbana,\u00a0 recostado sobre las monta\u00f1as,\u00a0 igual que toda la\u00a0 zona que no ha sido intervenida en los cerros orientales conserva una biodiversidad de fauna y flora de la que tanto se habla en Colombia; el parque fue una zona\u00a0 abandonada durante muchos a\u00f1os, donde \u00a0no se pod\u00eda construir \u00a0y debido\u00a0 a esto, se\u00a0 ha\u00a0 produjo un proceso de regeracion que ha permitido peque\u00f1as manchas de bosque secundario producto de las semillas que han esparcido las aves y peque\u00f1os mam\u00edferos, que han habitado el sector desde hace d\u00e9cadas;\u00a0 en el primer decenio del siglo XXI\u00a0 fue intervenido y se crearon unas circulaciones, se le puso iluminaci\u00f3n,\u00a0 m\u00e1s que un parque es una circulaci\u00f3n que conecta diversas calles, no tiene\u00a0 bancas, la intervenci\u00f3n fue traum\u00e1tica,\u00a0 para hacerla\u00a0 se tumbaron\u00a0\u00a0 muchos \u00e1rboles y palmas de corozo\u00a0 que fueron reemplazadas por arboles salidos de los viveros de la CDMB como guayacanes, palmas reales y otros, todos ellos \u00e1rboles de reforestaci\u00f3n maderera \u00a0\u00a0o de silvicultura urbana procedentes del sudeste asi\u00e1tico, ajenas al sitio donde se plantan, que tanto mal le han hecho \u00a0a las ciudades colombianas, casi todos estos \u00e1rboles\u00a0 han desaparecido por ser \u00e1rboles de vivero y necesitar constante mantenimiento, <a href=\"http:\/\/www.biodiversityreporting.org\/article.sub?docId=27810&amp;c=Colombia&amp;cRef=Colombia&amp;year=2008&amp;date=June%202007\">http:\/\/www.biodiversityreporting.org\/article.sub?docId=27810&amp;c=Colombia&amp;cRef=Colombia&amp;year=2008&amp;date=June%202007<\/a> todos los arbustos fueron talados y reemplazados por una \u00fanica cobertura verde\u00a0 llamada man\u00ed forrajero que no se ha dado\u00a0 o se ha dado mal por las caracter\u00edsticas de la zona, con el tiempo \u00a0el parque se recuper\u00f3 debido \u00a0el poco mantenimiento que se le hac\u00eda ; era una zona llena de vida\u00a0 en las ma\u00f1anas se ve\u00eda gran cantidad de p\u00e1jaros, mariposas\u00a0 y ardillas buscando su alimento de las plantas que se encontraban all\u00ed: \u00a0desafortunadamente solo el hombre vive en sitios con coberturas verdes bajas, como c\u00e9sped o man\u00ed forrajero que es la que actualmente trataron de imponer con poco \u00e9xito; los animales para poder sobrevivir necesitan ciertos \u00a0arbustos y plantas de peque\u00f1o tama\u00f1o\u00a0\u00a0 que la corta visi\u00f3n ecol\u00f3gica de las instituciones ambientales no producen y que son el alimento de las de especies asociadas a esta vegetaci\u00f3n.<\/p>\n<p><a href=\"http:\/\/www.solucionesespeciales.net\/Index\/Noticias\/374323-La-biodiversidad-se-amplia-en-Paris-Se-aceptan-malezas-en-los-parques-parisinos.aspx\">http:\/\/www.solucionesespeciales.net\/Index\/Noticias\/374323-La-biodiversidad-se-amplia-en-Paris-Se-aceptan-malezas-en-los-parques-parisinos.aspx<\/a>.<\/p>\n<p>La zona\u00a0\u00a0 se hab\u00eda convertido en un sitio lleno de p\u00e1jaros, mariposas ardillas y otros peque\u00f1os mam\u00edferos, que encontraban su alimento en varios \u00e1rboles de yarumo (p\u00e1jaros y ardillas), arbustos de lantana (mariposas), lulos silvestres (loros de anteojos) y palmas de corozo (loro de anteojos y aves).<\/p>\n<p>El\u00a0 viernes 11 de mayo del 2012\u00a0 \u00a0una cuadrilla de mantenimiento de la CDMB, llego al lugar, y procedi\u00f3 a\u00a0 talar todos los arboles de Yarumo varios de \u00a0ellos de m\u00e1s de 10 metros de alto, otros \u00e1rboles\u00a0 que hac\u00edan parte del bosque secundario buscados por los p\u00e1jaros por sus semillas, \u00a0tambi\u00e9n fueron cortados,\u00a0 el sotobosque tambi\u00e9n fue removido para buscar el man\u00ed forrajero al hacerlo\u00a0 docenas de lulos silvestres, peque\u00f1a palmas de corozo arbustos de lantanas y lilas silvestres \u00a0fuente de alimento\u00a0 de colibr\u00edes, fueron cortados,\u00a0 con\u00a0 esa tala desaparecieron muchas de las fuentes de alimentos de los\u00a0 animales de la zona, hacer \u201cmantenimiento\u201d como se le dice no puede seguir siendo una actividad depredadora que en lugar de enriquecer produce da\u00f1os ambientales y pone en peligro la vida de\u00a0 animales que dependen de las plantas taladas.<\/p>\n<p>La falta de pol\u00edticas ecol\u00f3gicas de las entidades gubernamentales, el poco conocimiento de las relaciones que se instauran entre fauna y flora, ponen en riesgo la supervivencia de\u00a0 muchos seres vivos que hacen parte de nuestro entorno.\u00a0 En la ciudad con un adecuado manejo de la cobertura \u00a0verde\u00a0\u00a0 y una revisi\u00f3n del modelo de parque urbano que incluyera no solo al hombre sino tambi\u00e9n nuestra fauna y flora acciones como esta\u00a0 no deber\u00edan \u00a0suceder, los parques urbanos no pueden seguir siendo\u00a0 sitios ajenos al lugar donde se implantan, copias de parques europeos que no ajustan su est\u00e9tica a la biodiversidad del lugar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &nbsp; Noooo \u00a0es la cuadrilla de mantenimiento de la corporaci\u00f3n de defensa de la meseta de Bucaramanga. El parque\u00a0 mirador del oriente por su posici\u00f3n geogr\u00e1fica en los l\u00edmites de la periferia urbana,\u00a0 recostado sobre las monta\u00f1as,\u00a0 igual que toda la\u00a0 zona que no ha sido intervenida en los cerros orientales conserva una biodiversidad &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/sin-categoria\/239-llegaron-los-barbaros-2\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-239","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKnu-3R","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/posts\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":3,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/posts\/239\/revisions"}],"predecessor-version":[{"id":243,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/posts\/239\/revisions\/243"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/categories?post=239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/paisaje-urbano\/wp-json\/wp\/v2\/tags?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}