{"id":24,"date":"2012-06-01T01:15:28","date_gmt":"2012-06-01T06:15:28","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/?p=24"},"modified":"2012-06-01T01:15:28","modified_gmt":"2012-06-01T06:15:28","slug":"tokio-blues","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/resto-del-mundo\/24-tokio-blues","title":{"rendered":"TOKIO BLUES"},"content":{"rendered":"<p>\u00a0<a href=\"http:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/files\/2012\/06\/tokioblues1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-40\" src=\"http:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/files\/2012\/06\/tokioblues1-1024x760.jpg\" alt=\"\" width=\"529\" height=\"372\" \/><\/a><\/p>\n<p>Adem\u00e1s de regresar 20 a\u00f1os en el tiempo, me volv\u00ed a impresionar leyendo. Parece, a simple vista, una historia de adolescentes vivida por adolescentes: algo as\u00ed como erecciones fallidas, noches cargadas de humo, toques de descontrol y una lucha por encontrar una motivaci\u00f3n para \u00abdarnos cuerda\u00bb, etc, etc, etc, pero en realidad es mucho m\u00e1s profundo el llanto, al menos\u00a0desde mi retr\u00f3grado punto de vista.<\/p>\n<p>Es ir m\u00e1s all\u00e1, as\u00ed sea desde el miope \u00e1ngulo de un veintea\u00f1ero. Es encontrar sentido a la carga emocional que representa vivir ese tiempo. Es jugar con fuego y quemarse para salir lastimado de por vida y no poder levantarse m\u00e1s.<\/p>\n<p>Leyendo Tokio Blues me di cuenta de que no estuve ni cerca de quemarme. Sent\u00ed un vac\u00edo, que nunca cre\u00ed tener, sent\u00ed envidia de la vida tan convulsa de sus personajes, en especial de Watanabe. Si estuvieramos tratando con un param\u00e9dico podr\u00eda decir que \u00abeste jovencito sali\u00f3 ileso\u00bb, pero creo que en realidad fue el m\u00e1s lastimado. Caminar no quiere decir estar vivo, a veces caminamos como muertos&#8230; o peor,\u00b4caminamos con muertos, que nos llevan a sus tumbas y nos dan de comer.<\/p>\n<p><a href=\"http:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/files\/2012\/06\/haruki-murakami.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-26 alignleft\" src=\"http:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/files\/2012\/06\/haruki-murakami-276x300.png\" alt=\"\" width=\"166\" height=\"239\" \/><\/a><\/p>\n<p>Ese es uno de los sentidos que Murakami acaba de despertar en m\u00ed. Si nos fijamos con atenci\u00f3n un momento en las personas que est\u00e1n a nuestro alrededor nos daremos cuenta de eso. Pero bueno, la historia nunca es presentada como de muertos, tal vez como de vivos s\u00ed. El t\u00edtulo original de este libro es &#8216;Norwegian wood&#8217;, canci\u00f3n de The Beatles, cuya letra me acaba de hacer parar los pelos.<\/p>\n<p>Es una historia impresionante, con pocos personajes, no m\u00e1s de 10, pero que cala hondo. Alg\u00fan editor cultural del diario El Pa\u00eds dijo sobre Murakami que era \u00abopi\u00e1ceo\u00bb, ahora le creo. Seguir\u00e9 comport\u00e1ndome como un muerto en medio de muertos. Aunque creo que nunca es tarde para arder, no s\u00e9 por qu\u00e9 insisto en clasificarla como Novela Negra, no lo es.<\/p>\n<p>Encontr\u00e9 que hay una pel\u00edcula (<a href=\"http:\/\/peliculas.labutaca.net\/tokio-blues\">http:\/\/peliculas.labutaca.net\/tokio-blues<\/a>), dirigida por Tran Anh Hung. Espero que no decepcione, aunque nunca hay que esperar mucho de estas adaptaciones. Tiene algo ya a su favor, y es que los actores japoneses est\u00e1n, s\u00ed o s\u00ed, cargados de carisma, lo cual no se puede dejar de lado en la historia. Volver\u00e9 con m\u00e1s Murakami,\u00a0no importa que descubra\u00a0un nuevo\u00a0vac\u00edo en m\u00ed\u00a0(\u30ce\u30eb\u30a6\u30a7\u30a4\u306e\u68ee.<\/p>\n<blockquote><p>\u00abLa muerte no se contrapone a la vida. La muerte hab\u00eda estado impl\u00edcita en mi ser desde un principio. Y \u00e9ste era un hecho que, por m\u00e1s que lo intent\u00e9, no pude olvidar. Aquella noche de mayo, cuando la muerte se llevo a Kizuki a sus diecisiete a\u00f1os, se llev\u00f3 una parte de m\u00ed\u00bb.<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Tokio Blues<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Adem\u00e1s de regresar 20 a\u00f1os en el tiempo, me volv\u00ed a impresionar leyendo. Parece, a simple vista, una historia de adolescentes vivida por adolescentes: algo as\u00ed como erecciones fallidas, noches cargadas de humo, toques de descontrol y una lucha por encontrar una motivaci\u00f3n para \u00abdarnos cuerda\u00bb, etc, etc, etc, pero en realidad es mucho &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/resto-del-mundo\/24-tokio-blues\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[8,9],"class_list":["post-24","post","type-post","status-publish","format-standard","hentry","category-resto-del-mundo","tag-murakami","tag-tokio","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKpE-o","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":13,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"predecessor-version":[{"id":43,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/posts\/24\/revisions\/43"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/otro-aburrido-club-de-lectura\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}