{"id":525,"date":"2008-12-07T16:33:19","date_gmt":"2008-12-07T21:33:19","guid":{"rendered":"http:\/\/www.bucaramanga.com\/blogs\/medio-ambiente\/?p=525"},"modified":"2008-12-07T16:33:19","modified_gmt":"2008-12-07T21:33:19","slug":"informacion-importante-sobre-espuma-de-poliestireno-expandido","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/creando-conciencia\/525-informacion-importante-sobre-espuma-de-poliestireno-expandido","title":{"rendered":"Informaci\u00f3n Importante Sobre Espuma de Poliestireno Expandido"},"content":{"rendered":"<div id=\"__ss_217260\" style=\"width: 425px; text-align: left;\"><a style=\"font:14px Helvetica,Arial,Sans-serif;display:block;margin:12px 0 3px 0;text-decoration:underline;\" title=\"contaminacion Unicel Tecnopor, telgopor, corcho blanco, poliestireno expandido foam  global\" href=\"http:\/\/www.slideshare.net\/promosmx.com\/unicel-tecnopor-telgopor-corcho-blanco-poliestireno-expandido-foam-contaminacion-global?type=powerpoint\">contaminacion Unicel Tecnopor, telgopor, corcho blanco, poliestireno expandido foam  global<\/a><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"407\" height=\"340\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/static.slideshare.net\/swf\/ssplayer2.swf?doc=unicel-tecnopor-telgopor-corcho-blanco-poliestireno-expandido-foam-contaminacion-global-1199301701289743-3&amp;stripped_title=unicel-tecnopor-telgopor-corcho-blanco-poliestireno-expandido-foam-contaminacion-global\" \/><\/object><\/p>\n<div style=\"font-size: 11px; font-family: tahoma,arial; height: 26px; padding-top: 2px;\">View SlideShare <a style=\"text-decoration:underline;\" title=\"View contaminacion Unicel Tecnopor, telgopor, corcho blanco, poliestireno expandido foam  global on SlideShare\" href=\"http:\/\/www.slideshare.net\/promosmx.com\/unicel-tecnopor-telgopor-corcho-blanco-poliestireno-expandido-foam-contaminacion-global?type=powerpoint\">presentation<\/a> or <a style=\"text-decoration:underline;\" href=\"http:\/\/www.slideshare.net\/upload?type=powerpoint\">Upload<\/a> your own. (tags: <a style=\"text-decoration:underline;\" href=\"http:\/\/slideshare.net\/tag\/global\">global<\/a> <a style=\"text-decoration:underline;\" href=\"http:\/\/slideshare.net\/tag\/contaminacion\">contaminacion<\/a>)<\/div>\n<\/div>\n<p>El EPS es un material pl\u00e1stico espumado, derivado del poliestireno y utilizado en el sector del envase. Se le conoce tambi\u00e9n en su versi\u00f3n m\u00e1s coloquial como tergopol\/telgopor (abreviatura de su descripci\u00f3n comercial \u00abtela gomosa porosa\u00bb), porespan, porexpan, poliexpan o corcho blanco, tambi\u00e9n se le llama estereof\u00f3n en Costa Rica, tecnopor en Per\u00fa, plumavit en Chile, icopor en Colombia, unicel en M\u00e9xico , espuma plast en Uruguay y espuma-flex en Ecuador.<\/p>\n<p><!--more--><\/p>\n<p>Muchos de los materiales que utilizamos diariamente representan una amenaza para el medio ambiente si no son usados con cuidado. Son aquellos que no se biodegradan o que tardan much\u00edsimos a\u00f1os en hacerlo. Entre ellos se encuentra un grupo muy grande de elementos reciclables cuyo impacto ambiental puede llegar a ser nulo si se introducen en procesos que permitan transformarlos en materiales nuevos para elaborar productos nuevos. El EPS es uno de ellos, es muy vers\u00e1til y beneficioso pero debe ser desechado con cautela. Por supuesto, si se recicla no es perjudicial para el medio ambiente pero si se vierte en basureros ocupa mucho espacio (15%) y no se degrada. Incrementa as\u00ed los efectos nocivos de los vertederos como los de propiciar enfermedades y miseria en las comunidades aleda\u00f1as y contaminar el planeta a un ritmo acelerado.<br \/>\nEn los oc\u00e9anos el da\u00f1o que el EPS puede causar es muy grande. Una vez cae al mar, por su densidad sale a flote y los peces lo confunden con comida. Al ingerirlo, llenan su sistema digestivo de un pl\u00e1stico no digerible que ocupa todo el espacio. As\u00ed, permanecen satisfechos y no pueden ingerir nada m\u00e1s y tras unas semanas, los peces mueren de inanici\u00f3n. Es clara pues la realidad de los efectos lesivos que puede llegar a tener sobre especies marinas.<br \/>\nEs fundamental evitar el vertimiento de EPS en basureros municipales y es a\u00fan m\u00e1s importante evitar a toda costa su descarga en oc\u00e9anos. El reciclaje es realmente la \u00fanica salida viable para manejar el EPS de manera responsable y actualmente las formas para hacerlo son asequibles a los individuos y a las empresas en muchos pa\u00edses. De hecho, existen m\u00e9todos para reciclar todos los tipos de pl\u00e1stico existentes. Es probable que las empresas dedicadas a reciclar materiales como este sean escasas pero si aumenta la demanda por parte de personas dispuestas a reciclar, aumentar\u00e1 la oferta de mecanismos para realizarlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>contaminacion Unicel Tecnopor, telgopor, corcho blanco, poliestireno expandido foam global View SlideShare presentation or Upload your own. (tags: global contaminacion) El EPS es un material pl\u00e1stico espumado, derivado del poliestireno y utilizado en el sector del envase. Se le conoce tambi\u00e9n en su versi\u00f3n m\u00e1s coloquial como tergopol\/telgopor (abreviatura de su descripci\u00f3n comercial \u00abtela gomosa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/medio-ambiente\/creando-conciencia\/525-informacion-importante-sobre-espuma-de-poliestireno-expandido\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[5,7,8],"tags":[24],"class_list":["post-525","post","type-post","status-publish","format-standard","hentry","category-creando-conciencia","category-generalidades","category-prevencion","tag-contaminacion","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKly-8t","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/comments?post=525"}],"version-history":[{"count":0,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/525\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/media?parent=525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/categories?post=525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/tags?post=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}