{"id":1506,"date":"2011-07-28T10:37:01","date_gmt":"2011-07-28T15:37:01","guid":{"rendered":"http:\/\/www.vliberal.com\/blogs\/medio-ambiente\/?p=1506"},"modified":"2011-07-28T10:37:01","modified_gmt":"2011-07-28T15:37:01","slug":"i-taller-analisis-ciclo-de-vida","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/sin-categoria\/1506-i-taller-analisis-ciclo-de-vida","title":{"rendered":"I TALLER ANALISIS CICLO DE VIDA"},"content":{"rendered":"<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1507\" src=\"http:\/\/www.vliberal.com\/blogs\/medio-ambiente\/wp-content\/uploads\/2011\/07\/Afiche-Ciclo-de-Vida-606x1024.jpg\" alt=\"Afiche Ciclo de Vida\" width=\"317\" height=\"534\" \/>\u201cUna alternativa para la evaluaci\u00f3n de los impactos ambientales\u201d.<br \/>\nEl An\u00e1lisis de Ciclo de Vida (ACV) es una metodolog\u00eda que permite identificar las cargas ambientales y los puntos en que \u00e9stas se generan durante el ciclo de vida de un producto, es decir, desde el origen de las materias primas hasta culminar la vida \u00fatil del producto \u201cDe la cuna a la Tumba\u201d. El prop\u00f3sito del taller es capacitar a estudiantes y profesionales relacionados con la profesi\u00f3n ambiental, en el manejo y aplicaci\u00f3n de la herramienta, que les permita tomar decisiones con criterio t\u00e9cnico en el mejoramiento de los procesos para la competitividad de la empresa.<br \/>\nFinalizado el taller, los participantes estar\u00e1n en capacidad de utilizar la herramienta SIMAPRO para el an\u00e1lisis del ciclo de vida, conocer las diversas metodolog\u00edas de evaluaci\u00f3n de impacto y elaborar escenarios para casos espec\u00edficos teniendo en cuenta la norma t\u00e9cnica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cUna alternativa para la evaluaci\u00f3n de los impactos ambientales\u201d. El An\u00e1lisis de Ciclo de Vida (ACV) es una metodolog\u00eda que permite identificar las cargas ambientales y los puntos en que \u00e9stas se generan durante el ciclo de vida de un producto, es decir, desde el origen de las materias primas hasta culminar la vida \u00fatil &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/medio-ambiente\/sin-categoria\/1506-i-taller-analisis-ciclo-de-vida\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1506","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKly-oi","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/1506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/comments?post=1506"}],"version-history":[{"count":0,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/1506\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/media?parent=1506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/categories?post=1506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/tags?post=1506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}