{"id":1222,"date":"2009-10-12T17:23:07","date_gmt":"2009-10-12T22:23:07","guid":{"rendered":"http:\/\/www.bucaramanga.com\/blogs\/medio-ambiente\/?p=1222"},"modified":"2009-10-12T17:23:07","modified_gmt":"2009-10-12T22:23:07","slug":"proyecto-de-investigacion-desinfeccion-en-agua-para-beneficio-del-cafe-por-medio-de-dosificacion-de-cloro-y-calefaccion-solar","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/general\/1222-proyecto-de-investigacion-desinfeccion-en-agua-para-beneficio-del-cafe-por-medio-de-dosificacion-de-cloro-y-calefaccion-solar","title":{"rendered":"Proyecto De Investigaci\u00f3n: Desinfecci\u00f3n En Agua Para Beneficio Del Caf\u00e9 Por Medio De Dosificaci\u00f3n De Cloro Y Calefacci\u00f3n Solar."},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.vliberal.com\/blogs\/medio-ambiente\/wp-content\/uploads\/2009\/10\/imag0587.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1224\" title=\"imag0587\" src=\"http:\/\/www.bucaramanga.com\/blogs\/medio-ambiente\/wp-content\/uploads\/2009\/10\/imag0587-300x224.jpg\" alt=\"\" width=\"196\" height=\"166\" \/><\/a>Por: Laura Astrid Sierra Vega y Didier Alfonso Rodr\u00edguez G\u00f3mez<\/p>\n<p style=\"text-align: justify;\">En el transcurso de los a\u00f1os los productores de caf\u00e9 en zonas rurales han venido utilizando grandes vol\u00famenes de agua para el beneficio y lavado del este sin tener en cuenta las condiciones in\u00edciales del fluido. Adicionando as\u00ed Coliformes fecales, y totales al grano y los subproductos de este.\u00a0 Por lo general las captaciones tambi\u00e9n se realizan para el abastecimiento de viviendas y sostenimiento de animales pasando por alto el incremento de enfermedades diarreicas, fiebres, epidemias y dem\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Los residuos l\u00edquidos son vertidos directamente en fuentes h\u00eddricas cercanas incrementando la carga org\u00e1nica de las mismas. Por ende se determin\u00f3 la eficiencia en sistemas de desinfecci\u00f3n por medio de dosificaci\u00f3n con cloro y calefacci\u00f3n solar para generar alternativas de tratamiento econ\u00f3mico para la desinfecci\u00f3n del agua mejorando la calidad de vida de las personas que se abastecen directamente de los cuerpos h\u00eddricos e incrementando la calidad tanto del producto como de los residuos l\u00edquidos generados en los procesos de beneficio y lavado del caf\u00e9. Facilitando as\u00ed la remoci\u00f3n de par\u00e1metros microbiol\u00f3gicos con un tratamiento posterior a las aguas resultantes de dichos procesos.<br \/>\nEn esta investigaci\u00f3n se plantean alternativas de desinfecci\u00f3n en agua para beneficio de caf\u00e9 y las personas que se abastecen directamente de las fuentes h\u00eddricas con soluciones econ\u00f3micas, ambientalmente viables y seguras. Estas alternativas fueron escogidas por el grupo investigador partiendo de una problem\u00e1tica ambiental que es muy com\u00fan en las fincas cafeteras estos sistemas fueron construidos partiendo de las caracter\u00edsticas de las fincas como lo es el aprovechamiento de la radiaci\u00f3n solar ya que ellas tienen un espacio determinado para el secado del caf\u00e9 el cual es una opci\u00f3n para\u00a0 ubicar el sistema de calefacci\u00f3n solar.\u00a0\u00a0\u00a0 Se realiz\u00f3 la comparaci\u00f3n de los sistemas de desinfecci\u00f3n por cloraci\u00f3n y calefacci\u00f3n solar determinando cual estructura es m\u00e1s eficiente en cuanto a remoci\u00f3n microbiol\u00f3gica.<!--more--><br \/>\nEl calefactor solar fue construido para un caudal de 0,81 ml\/s con un tiempo de retenci\u00f3n de media hora el cual fue insuficiente puesto que s\u00ed alcanzo la temperatura esperada y el tiempo\u00a0 requerido en \u00e9sta pero el tiempo de retenci\u00f3n fue muy corto para la carga de coliformes totales. A dem\u00e1s el tiempo de contacto del cloro fue muy corto debido a esto y al calentamiento presente en el dosificador y la dosis de hipoclorito la estructura no cumpli\u00f3 con la remoci\u00f3n necesaria para asegurar que el sistema cumple con lo requerido por el RAS. Adicionalmente el cloro residual libre s\u00ed cumpli\u00f3 con lo requerido por la legislaci\u00f3n y se tomo del ensayo de jarras pero se concluy\u00f3 que la dosis debe ser m\u00e1s alta pues a medida que hay carga microbiol\u00f3gica es necesario adicionarle el cloro; el cual debe agreg\u00e1rsele un exceso ya que a mayor carga mas oxidaci\u00f3n y degradaci\u00f3n de materia org\u00e1nica lo cual indica que la dosis optima arrojada por las\u00a0 pruebas de tratabilidad es muy baja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Laura Astrid Sierra Vega y Didier Alfonso Rodr\u00edguez G\u00f3mez En el transcurso de los a\u00f1os los productores de caf\u00e9 en zonas rurales han venido utilizando grandes vol\u00famenes de agua para el beneficio y lavado del este sin tener en cuenta las condiciones in\u00edciales del fluido. Adicionando as\u00ed Coliformes fecales, y totales al grano y &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/medio-ambiente\/general\/1222-proyecto-de-investigacion-desinfeccion-en-agua-para-beneficio-del-cafe-por-medio-de-dosificacion-de-cloro-y-calefaccion-solar\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[6,9],"tags":[37],"class_list":["post-1222","post","type-post","status-publish","format-standard","hentry","category-general","category-que-podemos-hacer","tag-que-podemos-hacer","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKly-jI","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":0,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/medio-ambiente\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}