{"id":91,"date":"2019-11-15T01:18:12","date_gmt":"2019-11-15T00:18:12","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/laurometro\/?p=91"},"modified":"2019-11-15T20:59:45","modified_gmt":"2019-11-15T19:59:45","slug":"consenso-la-llave-del-exito-de-los-gobernantes","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/laurometro\/2019\/11\/15\/consenso-la-llave-del-exito-de-los-gobernantes\/","title":{"rendered":"Consenso, la llave del \u00e9xito de los gobernantes."},"content":{"rendered":"\n<p>El primero de enero se posesionan los nuevos mandatarios regionales y su buena gesti\u00f3n ser\u00e1 la clave de su \u00e9xito. No obstante, hay un aliado olvidado que puede ser la llave para alcanzarlo: generar consensos y esto lo pueden lograr a trav\u00e9s de una buena comunicaci\u00f3n gubernamental.<\/p>\n\n\n\n<p>La popularidad de los gobernantes no es un dato que se deba subestimar porque compromete autom\u00e1ticamente la aprobaci\u00f3n de su gesti\u00f3n. Aqu\u00ed es donde est\u00e1 el misterio: sin aprobaci\u00f3n no hay respaldo y sin respaldo no se facilita la gobernabilidad. Para que una administraci\u00f3n pueda tomar decisiones y ejecutarlas, es necesario que tenga gobernabilidad, de lo contrario se encontrar\u00e1 con muchos obst\u00e1culos para cumplir con su plan de gobierno.<\/p>\n\n\n\n<p>Vamos a lo pr\u00e1ctico: desde el a\u00f1o 2009 ning\u00fan alcalde en Bogot\u00e1 ha logrado una popularidad que al menos alcance el 50%, esto se ve reflejado en las varias revocatorias de mandato que se han puesto en marcha y en las numerosas acciones contra la administraci\u00f3n para frenar la ejecuci\u00f3n de los proyectos que a medias, o que avanzan a paso lento. Bogot\u00e1 sufre de un mal ambiente que no le permite generar m\u00e1s desarrollo.<\/p>\n\n\n\n<p>Por otro lado, hay casos como el del alcalde de Barranquilla y el gobernador del Atl\u00e1ntico en donde la aprobaci\u00f3n es mucho mejor y los resultados son otros. En Barranquilla, Alex Char lleg\u00f3 a niveles de aprobaci\u00f3n del 95% gracias a una mezcla entre resultados, gesti\u00f3n y comunicaci\u00f3n. En el Atl\u00e1ntico ha sido m\u00e1s f\u00e1cil cumplir con los planes de gobierno, por eso no es resultado del azar que esta regi\u00f3n sea la de mayor potencial de crecimiento en el pa\u00eds. <\/p>\n\n\n\n<p>Las redes sociales abrieron un nuevo espacio de comunicaci\u00f3n y debate que ha sido permeado por una din\u00e1mica de campa\u00f1a permanente, acompa\u00f1ada de altos niveles de negatividad en la narrativa. Los conflictos que surgen en el mundo digital se trasladaron al mundo real y el resultado de esto ha sido la construcci\u00f3n de ambientes polarizados, muy perjudiciales para gobernar. En las \u00faltimas campa\u00f1as regionales el aumento de estrategias de comunicaci\u00f3n negativa crearon ambientes tan apocal\u00edpticos y brechas tan profundas que el futuro de los pr\u00f3ximos gobernantes es incierto, porque los cambios no se dan de la noche a la ma\u00f1ana y los ciudadanos pierden f\u00e1cilmente la esperanza. Ya hay quienes se est\u00e1n oponiendo a los programas de los futuros mandatarios cuando ni siquiera se han posesionado.<\/p>\n\n\n\n<p>El consenso es la herramienta m\u00e1s olvidada pero m\u00e1s poderosa para gobernar. Generar consensos permite disminuir los bloqueos legislativos, ciudadanos o de opini\u00f3n para gobernar tranquilamente. Una buena comunicaci\u00f3n gubernamental va a permitir generar el m\u00e1ximo consenso posible. Esto no quiere decir que no existan disensos, claro que los habr\u00e1, pero ser\u00e1n mas controlables. Por eso los pr\u00f3ximos alcaldes y gobernadores, deber\u00e1n despojarse de la din\u00e1mica de campa\u00f1a permanente, quitarse la camiseta del marketing electoral y ponerse la de la comunicaci\u00f3n gubernamental.<\/p>\n\n\n\n<p>Insisto en que hay que confiarle esta tarea a un equipo de expertos. La comunicaci\u00f3n pol\u00edtica deber ser cada vez m\u00e1s profesionalizada: no es lo mismo hacer comunicaci\u00f3n para una marca comercial que para un gobierno, empezando porque lo que est\u00e1 en juego no es el crecimiento de las ventas sino el futuro de los ciudadanos. Tampoco los analistas son expertos en comunicaci\u00f3n. Lo importante no debe ser la forma sino el fondo. No existen buenos gobiernos que comuniquen mal, ni malos que lo hagan bien; pero una buena gesti\u00f3n de la comunicaci\u00f3n gubernamental, con equipos preparados para poner en marcha estrategias responsables, serias y eficaces, en definitiva, s\u00ed puede aportar a la construcci\u00f3n de un mejor ambiente para gobernar. <\/p>\n\n\n\n<p>Una m\u00e1s y me voy: Hay figuras pol\u00edticas que en su af\u00e1n de poder se est\u00e1n llevando a la ciudadan\u00eda por delante con sus narrativas de odio. A ellos hay que exigirles responsabilidad. Si permitimos que nos dividan nos ser\u00e1 mucho m\u00e1s dif\u00edcil avanzar.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primero de enero se posesionan los nuevos mandatarios regionales y su buena gesti\u00f3n ser\u00e1 la clave de su \u00e9xito. No obstante, hay un aliado olvidado que puede ser la llave para alcanzarlo: generar consensos y esto lo pueden lograr a trav\u00e9s de una buena comunicaci\u00f3n gubernamental. La popularidad de los gobernantes no es un &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/laurometro\/2019\/11\/15\/consenso-la-llave-del-exito-de-los-gobernantes\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[21,93,83,103,94,100,69,19,102,97,95,99,96,98],"class_list":["post-91","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-alcaldia","tag-alex-char","tag-bogota","tag-buena-comunicacion","tag-char","tag-clave","tag-comunicacion-gubernamental","tag-comunicacion-politica","tag-consejos","tag-consenso","tag-eduardo-verano","tag-exito","tag-gobernador","tag-popularidad","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/posts\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/posts\/91\/revisions\/94"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/laurometro\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}