{"id":197,"date":"2015-07-16T14:47:58","date_gmt":"2015-07-16T19:47:58","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/?p=197"},"modified":"2015-07-16T14:47:58","modified_gmt":"2015-07-16T19:47:58","slug":"de-la-pasarela-a-la-calle","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/2015\/07\/16\/de-la-pasarela-a-la-calle\/","title":{"rendered":"De la pasarela a la calle."},"content":{"rendered":"<p>Este blog se llama \u00abLa imagen no es s\u00f3lo moda\u00bb y cada d\u00eda que sigo ejerciendo como Consultora de Imagen, lo sigo confirmando. En repetidas ocasiones durante las sesiones personales con mis clientes, veo que compran prendas que est\u00e1n exhibidas en las vitrinas de las tiendas de ropa, pues consideran que est\u00e1n de moda, pero muchas veces se nos olvida que las modas no son para todo el mundo. Esto depende de muchos factores como; la forma del cuerpo, los colores, los estampados, el tipo de tela, entre otros.<\/p>\n<p>Es por esto que me he dado a la tarea de buscar entre\u00a0las tendencias que salieron en las pasarelas de las colecciones primavera-verano 2015, cu\u00e1les son aquellas tendencias que aplican para casi todos los casos y algunas recomendaciones en particulares seg\u00fan la forma del cuerpo de cada persona:<\/p>\n<p>1. Una tendencia f\u00e1cil de renovar cada temporada son los zapatos, pues los puedes usar repetidamente en una semana, dandole un alto uso en una misma temporada. En las calles de New York sigue siendo el factor principal la comodidad, marcando la pauta los zapatos planos, medio puntudos y con correa en el tal\u00f3n.\u00a0Esta tendencia es m\u00e1s formal que las bailarinas y menos incomoda que los tacones.<\/p>\n<p>Si tienes piernas anchas con tobillos gruesos, te recomiendo evitar esta moda, pues segura va a ser incomoda y adem\u00e1s te har\u00e1 lucir m\u00e1s anchos los tobillos, agreg\u00e1ndote peso.<\/p>\n<p><a href=\"http:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.01-PM.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-198\" src=\"http:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.01-PM-300x117.png\" alt=\"Zapatos con banda en tobillo\" width=\"300\" height=\"117\" srcset=\"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.01-PM-300x117.png 300w, https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.01-PM-900x351.png 900w, https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.01-PM.png 965w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>2.Otra\u00a0forma de actualizar el guardarropas sin invertir mucho dinero son los collares. En donde tenemos de vuelta los Chokers o gargantillas que fueron muy famosas en los a\u00f1os 90&#8217;s, pero que en esta ocasi\u00f3n vuelven con tama\u00f1os grandes, en colores plateados o dorados y muy simples. Si la forma de tu cara es redonda o tienes el cuello corto, evita el uso de este tipo de accesorios, pues lo que van a hacer es acortarte el cuello, haci\u00e9ndote lucir con unos cuantos kilos dem\u00e1s.<\/p>\n<p><a href=\"http:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.27-PM.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-200 aligncenter\" src=\"http:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.27-PM-300x202.png\" alt=\"moda collares\" width=\"300\" height=\"202\" srcset=\"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.27-PM-300x202.png 300w, https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.27-PM-900x606.png 900w, https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/files\/2015\/06\/Screen-Shot-2015-06-23-at-5.07.27-PM.png 903w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Otra tendencia son los pendientes grandes, colgando de cadenas delgadas (para darle m\u00e1s importancia al pendiente). Esta tendencia es perfecta para agregar un poco de color al outfit, pues se encuentran en el mercado todo tipo de piedras y colores. La moda Boho-chic sigue siendo tendencia esta temporada, as\u00ed que puedes tener las dos en un s\u00f3lo accesorio usando un collar bohemio con piedras naturales y en colores pasteles.<\/p>\n<p>Si tienes grandes pechos,\u00a0aseg\u00farate que el largo de la cadena quede m\u00e1s arriba o abajo del busto, pues de lo contrario vas a llamar la atenci\u00f3n en el pecho m\u00e1s que en la cara.<\/p>\n<p>Si tienes dudas con \u00a0respecto a alguna tendencia que te gusta y no sabes si te queda bien, escr\u00edbeme a mena@propersonalbrand.com.<\/p>\n<p>Mena Gonz\u00e1lez<\/p>\n<p>Consultora de Imagen y Marca Personal.<\/p>\n<p>www.ProPersonalBrand.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este blog se llama \u00abLa imagen no es s\u00f3lo moda\u00bb y cada d\u00eda que sigo ejerciendo como Consultora de Imagen, lo sigo confirmando. En repetidas ocasiones durante las sesiones personales con mis clientes, veo que compran prendas que est\u00e1n exhibidas en las vitrinas de las tiendas de ropa, pues consideran que est\u00e1n de moda, pero &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/2015\/07\/16\/de-la-pasarela-a-la-calle\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,2],"tags":[5,11,17,13,43,15,4,6,42,7,18],"class_list":["post-197","post","type-post","status-publish","format-standard","hentry","category-imagen-personal","category-moda","tag-consultoria-de-imagen","tag-estilo-personal","tag-fashion","tag-formas-del-cuerpo","tag-imagen-personal","tag-imagen-profesional","tag-marca-personal","tag-mena-gonzalez","tag-moda","tag-pro-personal-brand","tag-tendencias","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/posts\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":209,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/posts\/197\/revisions\/209"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/la-imagen-no-es-solo-moda\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}