{"id":131,"date":"2016-09-19T09:03:28","date_gmt":"2016-09-19T14:03:28","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/?p=131"},"modified":"2016-09-19T11:26:28","modified_gmt":"2016-09-19T16:26:28","slug":"131","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/2016\/09\/19\/131\/","title":{"rendered":"LA PUERTA DE ACCESO AL M\u00c1XIMO POTENCIAL CREATIVO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-132 size-full\" src=\"http:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/GP.jpg\" alt=\"gp\" width=\"1078\" height=\"516\" srcset=\"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/GP.jpg 1078w, https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/GP-300x144.jpg 300w, https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/GP-768x368.jpg 768w, https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/GP-1024x490.jpg 1024w\" sizes=\"auto, (max-width: 1078px) 100vw, 1078px\" \/><\/p>\n<p>Hoy d\u00eda existen las m\u00e1s diversas ideas sobre c\u00f3mo potenciar la creatividad. Y en tal sentido si es este nuestro objetivo, procuramos incorporar nuevas tendencias, actividades, nuevos pensamientos o nuevas filosof\u00edas. Sin embargo, existe una frase que com\u00fanmente usamos para hacer referencia a esos momentos en que se nos ocurre algo genial, una idea distinta o la soluci\u00f3n a un problema: &#8216;\u00a1Se me prendi\u00f3 el bombillo!&#8217; Esta, aunque no lo sepamos, es la met\u00e1fora que hace referencia al encendido de una gl\u00e1ndula que se encuentra justo en el centro de nuestro cerebro y que es la responsable, entre otras funciones, de disparar el potencial creativo de los seres humanos: la Gl\u00e1ndula Pineal, conocida tambi\u00e9n como Ep\u00edfisis.<\/p>\n<p>Esta gl\u00e1ndula, cuyo tama\u00f1o no supera al de una lenteja y que debe su nombre a la similitud de su forma respecto a la semilla del pino, es la responsable entre otras funciones, de la producci\u00f3n de Melatonina, mejor conocida como la \u201cHormona de la Eterna Juventud\u201d, tiene poder inmunol\u00f3gico frente a la mayor\u00eda de las enfermedades, act\u00faa como regenerador celular y es reguladora del sue\u00f1o y los ciclos biol\u00f3gicos.<\/p>\n<p>A\u00fan cuando su actividad resulta fundamental para el funcionamiento del organismo, los cient\u00edficos han determinado que se empieza a atrofiar naturalmente entre los 7 y 8 a\u00f1os de edad. Sin embargo, existe un m\u00e9todo para reactivarla creado hace 25 a\u00f1os por la periodista cient\u00edfica de origen chileno Fresia Castro, quien es autora de 5 libros, el primero de ellos titulado \u201cEl Cielo Est\u00e1 Abierto\u201d, un\u00a0<em>bestseller<\/em>\u00a0que describe a profundidad la t\u00e9cnica.<\/p>\n<p>Cristi\u00e1n Vidal Rojas, Ingeniero chileno con estudios en Psicolog\u00eda, quien ha sido preparado y entrenado directamente por Fresia Castro y lleva 16 a\u00f1os siendo Instructor Internacional del M\u00e9todo de Activaci\u00f3n Interna de Gl\u00e1ndula Pineal, estar\u00e1 en la Universidad Aut\u00f3noma de Bucaramanga (UNAB) los d\u00edas 18, 19 y 20 de Octubre, impartiendo este seminario, cuyos beneficios desde el punto de vista f\u00edsico, mental y emocional, ya disfrutan m\u00e1s de 400.000 personas en el mundo.<\/p>\n<p>A trav\u00e9s de un taller experiencial de tres d\u00edas de duraci\u00f3n, que incorpora informaci\u00f3n y ejercicios no convencionales, brindar\u00e1 a los participantes las herramientas para restablecer su potencial creativo &#8211; lo que se traduce en nuevas ideas, propuestas y soluciones &#8211; recuperar y sanar memorias, entrenar la atenci\u00f3n, activar el circuito de conexi\u00f3n superior y elevar la calidad de sus sentimientos, lo que deriva en mayores niveles de felicidad y equilibrio en quienes lo experimentan.<\/p>\n<p>Para tomar este seminario no se requiere tener ninguna formaci\u00f3n ni preparaci\u00f3n espec\u00edfica. Est\u00e1 dirigido a toda persona que quiera potenciar sus habilidades y talentos y desarrollar sus capacidades creativas, que quiera superar ciertas patolog\u00edas y mejorar su calidad de vida o equilibrar sus emociones y experimentar un estado de plenitud.<\/p>\n<p>\u201cUna de las intervenciones m\u00e1s interesantes de esta t\u00e9cnica es su incorporaci\u00f3n dentro de las organizaciones como una herramienta de innovaci\u00f3n y potenciador de la creatividad, pues empodera a sus integrantes y les ofrece estados de equilibrio para tomar las mejores decisiones\u201d, afirma Vidal, quien agrega que \u201ccuando muchos seres se agrupan con un mismo objetivo, con actos creativos de una misma potencia, son capaces de crear una nueva realidad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Maritza Rodr\u00edguez<\/strong><\/em><\/p>\n<p>Directora Ananda Center<\/p>\n<p>maritzarodriguez@anandacenter.co<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hoy d\u00eda existen las m\u00e1s diversas ideas sobre c\u00f3mo potenciar la creatividad. Y en tal sentido si es este nuestro objetivo, procuramos incorporar nuevas tendencias, actividades, nuevos pensamientos o nuevas filosof\u00edas. Sin embargo, existe una frase que com\u00fanmente usamos para hacer referencia a esos momentos en que se nos ocurre algo genial, una idea &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/2016\/09\/19\/131\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":19,"featured_media":133,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[128,130,131,127,129],"tags":[48,132,39,134,133],"class_list":["post-131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cerebro","category-epifisis","category-fresia-castro","category-glandula-pineal","category-melatotina","tag-cerebro","tag-ciencia","tag-creatividad","tag-hormona","tag-innovacion","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/files\/2016\/09\/la-gl\u00e1ndula-pineal.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":3,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"predecessor-version":[{"id":136,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/posts\/131\/revisions\/136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/media\/133"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/el-arte-de-ser-humanos\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}