{"id":862,"date":"2012-08-22T15:08:56","date_gmt":"2012-08-22T20:08:56","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/?p=862"},"modified":"2012-08-22T15:16:35","modified_gmt":"2012-08-22T20:16:35","slug":"no-mas-memes","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/redes-sociales\/862-no-mas-memes","title":{"rendered":"No m\u00e1s \u2018memes\u2019"},"content":{"rendered":"<p>Al principio fueron graciosos. Ya no. Hay una sobresaturaci\u00f3n de los chistes tipo \u2018meme\u2019.<\/p>\n<p>Es dif\u00edcil que un cibernauta del mundo moderno no se haya topado al menos una vez con un llamado \u2018meme\u2019. Basados en un video, frase o cualquier tipo de material viral que circule en la red, nace por lo general uno de estos ejemplares, definidos como: \u201c(\u2026) un fen\u00f3meno que se populariza por Internet. Se trata de un hecho relacionado con cualquier tem\u00e1tica que se replica a una velocidad de v\u00e9rtigo por toda la Red y que en pocas horas da la vuelta al mundo\u201d<a href=\"http:\/\/www.pisitoenmadrid.com\/blog\/2011\/06\/meme-historia-de-los-fenomenos-de-internet\/\"><em><strong>1<\/strong><\/em><\/a>.<!--more--><\/p>\n<p>Sin embargo, el fen\u00f3meno ya es demasiado popular. Pareciera como si el sentido del humor de los m\u00e1s j\u00f3venes, quienes son los que m\u00e1s usan este recurso facilista para chistes, se limitara a ese tipo de lenguaje. Los chistes son iguales, las interacciones similares, los personajes se repiten una y otra vez sin parar. Y a\u00fan as\u00ed, el contenido de este material no mejora.<\/p>\n<p>No estoy en contra de lo viral, pero s\u00ed de lo repetitivo, pues llega un punto donde las burlas armadas con \u2018memes\u2019 son las mismas con los mismos, en aquel escenario virtual diciendo exactamente lo que han dicho las cien veces pasadas.\u00a0<a href=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2012\/08\/memes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-863\" title=\"memes\" src=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2012\/08\/memes-300x243.jpg\" alt=\"\" width=\"240\" height=\"194\" srcset=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2012\/08\/memes-300x243.jpg 300w, https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2012\/08\/memes.jpg 403w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n<p>Cada vez hay m\u00e1s p\u00e1ginas y en distintos idiomas que popularizan esta forma de narrar casi cualquier suceso de un ser humano. Y s\u00ed, son graciosos, pero tanta proliferaci\u00f3n de \u2018memes\u2019 podr\u00eda llegar a ser algo negativo. Muchos nacen con una intenci\u00f3n y son graciosos esa vez, sin embargo luego, surgen todo tipo de mezclas y nuevas versiones que terminan alterando lo que una vez esa imagen quiso decir.<\/p>\n<p>Un par de \u2018memes\u2019 no perjudican a nadie, pero si no se buscan nuevas maneras de innovar y contar historias graciosas y virales en otro formato, la creatividad cibern\u00e9tica se ver\u00e1 uniformada y encasillada a un est\u00e1ndar mon\u00f3tono y soso. Es un proceso similar al que se vio alguna vez con los realities, que en un principio se supon\u00eda que eran un formato televisivo arriesgado e innovador, aunque luego de ser profanado por todos los canales se convirti\u00f3 en una telenovela m\u00e1s, llena de clich\u00e9s y estereotipos.<\/p>\n<p>Es posible, que si los creadores de sus \u2018memes\u2019 no se esmeran en buscar otra forma creativa de burlarse de la realidad mundial, el formato deje de ser atractivo y se estanque. O que por el contrario, llegue otro lenguaje cibern\u00e9tico dispuesto a reemplazarlo. De cualquier manera es importante reflexionar sobre la narrativa de lo que cuentan los internautas y c\u00f3mo deber\u00eda evolucionar esta expresi\u00f3n. Lo m\u00e1s valioso de Internet es su gran rapidez y f\u00e1cil acceso, que le permite a cualquiera contar la historia que le plazca. Y al mismo tiempo, nos facilita aprender de lo que otros tienen para relatar. Pero, \u00bfy si todos cuentan lo mismo?, \u00bfqu\u00e9 se supone que vamos a aprender?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c1ngela Boh\u00f3rquez<\/strong><br \/>\nAsesora<br \/>\n<a href=\"http:\/\/www.colombiadigital.net\/\">Corporaci\u00f3n Colombia Digital<\/a><br \/>\nangela.bohorquez.s@gmail.com<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al principio fueron graciosos. Ya no. Hay una sobresaturaci\u00f3n de los chistes tipo \u2018meme\u2019. Es dif\u00edcil que un cibernauta del mundo moderno no se haya topado al menos una vez con un llamado \u2018meme\u2019. Basados en un video, frase o cualquier tipo de material viral que circule en la red, nace por lo general uno &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/redes-sociales\/862-no-mas-memes\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[16],"tags":[373,370,99,612,372,615],"class_list":["post-862","post","type-post","status-publish","format-standard","hentry","category-redes-sociales","tag-chistes-virtuales","tag-ciberespacio","tag-creatividad","tag-innovacion","tag-memes","tag-redes-sociales","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKmq-dU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":3,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/862\/revisions"}],"predecessor-version":[{"id":865,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/862\/revisions\/865"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/media?parent=862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/categories?post=862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/tags?post=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}