{"id":413,"date":"2010-07-07T15:56:01","date_gmt":"2010-07-07T20:56:01","guid":{"rendered":"http:\/\/www.vliberal.com\/blogs\/corporacion-colombia-digital\/?p=413"},"modified":"2010-07-07T15:56:01","modified_gmt":"2010-07-07T20:56:01","slug":"radiografia-virtual-involuntaria","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/redes-sociales\/413-radiografia-virtual-involuntaria","title":{"rendered":"Radiograf\u00eda virtual involuntaria"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-415 alignnone\" src=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2010\/07\/privacidad.jpg\" alt=\"91805593\" width=\"370\" height=\"462\" srcset=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2010\/07\/privacidad.jpg 370w, https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2010\/07\/privacidad-240x300.jpg 240w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Hace poco habl\u00e9 con una de mis amigas m\u00e1s cercanas de mi ciudad natal, Barranquilla, con quien cabe anotar, llevaba m\u00e1s de seis meses sin tener informaci\u00f3n sobre su existencia. En dicha llamada, me cont\u00f3 sobre su trabajo, su familia y su relativamente nuevo novio con quien est\u00e1 m\u00e1s que contenta y enamorada. <em>\u201cOye, me gustar\u00eda conocerlo, \u00bfPor qu\u00e9 no publicas una foto de \u00e9l en Facebook?\u201d<\/em>, le dije, a lo que ella me respondi\u00f3:<em> \u201cLa gente es muy envidiosa. Prefiero mantener mi vida privada como lo que es: privada\u201d<\/em>.<\/p>\n<p style=\"text-align: justify\">Sabia respuesta. Ella es de esas personas que tiene poca informaci\u00f3n en su perfil de Facebook, pone de vez en cuando una que otra foto, alg\u00fan estatus con informaci\u00f3n que necesita y no se la pasa de wall en wall poniendo a qui\u00e9n quiere y a qui\u00e9n no. Su actitud, posiblemente vista por algunos como arisca y asocial en un mundo que ha reducido la interacci\u00f3n a clics y m\u00e1s clics, es en realidad sumamente prudente y cuidadosa con su imagen virtual.<\/p>\n<p style=\"text-align: justify\">Se ha preguntando alguna vez, \u00bfQu\u00e9 clase de imagen proyecta a trav\u00e9s de sus redes? Hace poco, le\u00ed en un especial de la revista Semana destac\u00f3 lo siguiente: <em>\u201cUn estudio hecho por Ralph Gross y Alessandro Acquisti, de la Universidad Carnegie Mellon en Estados Unidos, sorprendi\u00f3 al mostrar c\u00f3mo se pod\u00eda predecir el n\u00famero de Seguridad Social, que se usa para autenticar las transacciones bancarias y las tarjetas de cr\u00e9dito en Estados Unidos, solo usando informaci\u00f3n publicada en diferentes fuentes, incluidas las redes sociales, y con datos tan inocentes como el d\u00eda de nacimiento y la ciudad o el estado de residencia. Otro, igual de controversial, fue hecho por dos estudiantes del Instituto Tecnol\u00f3gico de Massachussetts (MIT), quienes lograron, solo usando datos de Facebook, predecir si una persona era gay\u201d<\/em>.<\/p>\n<p style=\"text-align: justify\">Dicho art\u00edculo, me ha puesto a reflexionar sobre lo que comparto o no a trav\u00e9s de Facebook, la red social de mi preferencia de la que m\u00e1s he sido defensora hasta el momento. Creo yo que, aunque el tema ya est\u00e1 bastante repetido, mucha gente no comprende que Facebook o Flickr son una hoja de vida adicional a la que est\u00e1n presentando. Incluso, es bien sabido que diversas empresas buscan en la Red los perfiles de candidatos a puestos laborales con el fin de ampliar la informaci\u00f3n recibida en una entrevista.<\/p>\n<p style=\"text-align: justify\">As\u00ed que tenga cuidado con lo que publica: una frase odioso, una foto pasado de tragos o una ubicaci\u00f3n donde planea pasar sus pr\u00f3ximas vacaciones son bombas de tiempo que pueden estallar de manera desafortunada si no somos precavidos. Simplemente, analice lo que publica y preg\u00fantese: \u00bfEstar\u00e9 proyectando la imagen de quien realmente soy a trav\u00e9s de los contenidos que expongo?<\/p>\n<p style=\"text-align: justify\"><strong>Referencia<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>1. <\/strong>Tomado de: <a href=\"http:\/\/www.semana.com\/noticias-vida-moderna\/alguien-mira\/140954.aspx\">http:\/\/www.semana.com\/noticias-vida-moderna\/alguien-mira\/140954.aspx<\/a><\/p>\n<p style=\"text-align: justify\"><strong>Angela Boh\u00f3rquez<\/strong><br \/>\nDirectora de contenidos del Portal Web<br \/>\nCorporaci\u00f3n Colombia Digital<br \/>\n<a href=\"mailto:angelabohorquez@colombiadigital.net\">angelabohorquez@colombiadigital.net<\/a><br \/>\n<a href=\"http:\/\/www.colombiadigital.net\/\">www.colombiadigital.net<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace poco habl\u00e9 con una de mis amigas m\u00e1s cercanas de mi ciudad natal, Barranquilla, con quien cabe anotar, llevaba m\u00e1s de seis meses sin tener informaci\u00f3n sobre su existencia. En dicha llamada, me cont\u00f3 sobre su trabajo, su familia y su relativamente nuevo novio con quien est\u00e1 m\u00e1s que contenta y enamorada. \u201cOye, me &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/redes-sociales\/413-radiografia-virtual-involuntaria\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[16],"tags":[89,173,618,246,255,256,268,615],"class_list":["post-413","post","type-post","status-publish","format-standard","hentry","category-redes-sociales","tag-confidencial","tag-informacion","tag-internet","tag-personas","tag-privacidad","tag-privado","tag-publico","tag-redes-sociales","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKmq-6F","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/comments?post=413"}],"version-history":[{"count":0,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/413\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/media?parent=413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/categories?post=413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/tags?post=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}