{"id":1165,"date":"2013-12-24T16:59:32","date_gmt":"2013-12-24T21:59:32","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/?p=1165"},"modified":"2013-12-24T16:59:32","modified_gmt":"2013-12-24T21:59:32","slug":"la-generacion-que-se-quita-y-pone-el-chip","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/cultura-2\/1165-la-generacion-que-se-quita-y-pone-el-chip","title":{"rendered":"La generaci\u00f3n que se quita y pone el chip"},"content":{"rendered":"<p>Las generaciones de los \u00faltimos 20 a\u00f1os han sido marcadas por la explosi\u00f3n digital de las tecnolog\u00edas de la informaci\u00f3n.<!--more--><\/p>\n<p>Alguien se atrevi\u00f3 a darle nombre propio a las generaciones. Supongo que de acuerdo a una serie de factores y caracter\u00edsticas espec\u00edficas, quienes integran el grupo se destacan por el contexto y los sucesos que determinaron la construcci\u00f3n de su imaginario colectivo. Que su relaci\u00f3n con el medio, la cultura, la sociedad, las tecnolog\u00edas; qu\u00e9 su capacidad de evolucionar, adaptarse, quedarse estancados, seguir las reglas\u2026 en fin, toda una serie de cualidades encasilladas en una gran tabla imaginaria, a la que cada quien le hace un \u201ccheck list\u201d.<\/p>\n<p>Cada generaci\u00f3n busca diferenciarse de su anterior y por supuesto evolucionar. Dicen que pertenezco a la Generaci\u00f3n Y, la de los nativos digitales. Nacimos cuando Internet empezaba a despegar, cuando los videojuegos estaban en su apogeo, las videoconsolas, la aparici\u00f3n de los primeros celulares, a los que muchos dimos el calificativo de \u201cpanelas\u201d, por su gran tama\u00f1o.<\/p>\n<p>Hemos visto como a medida que pasan los a\u00f1os, todo se hace m\u00e1s cercano y a la vez peque\u00f1o. No creo cien por ciento en la astrolog\u00eda, sin embargo creo que existe cierta m\u00edstica en la alineaci\u00f3n astral de los planetas o como se le quiera llamar que de alguna manera (no s\u00e9 c\u00f3mo) permite establecer una serie de cualidades entre los individuos nacidos en ciertas \u00e9pocas. En \u00faltimas se trata de definir personalidades, no es m\u00e1s nada. Algo similar sucede con el tema de las generaciones.\u00a0<a href=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/12\/Apropiacion_sociedad.jpg\"><br \/>\n<\/a> <a href=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/12\/generacionY.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1167\" alt=\"generacionY\" src=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/12\/generacionY-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/12\/generacionY-300x200.jpg 300w, https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/12\/generacionY.jpg 507w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Cada una de ellas est\u00e1 agrupada bajo una serie de aspectos que identifican a los hombres y mujeres nacidos de tal a tal fecha. En mi caso, <a href=\"http:\/\/web.jet.es\/danet\/generaciony.htm\" target=\"_blank\">la Generaci\u00f3n Y<\/a>, nos llaman apasionados, emprendedores, con capacidad de adaptarnos f\u00e1cilmente a los cambios, buscamos hacer siempre lo que nos gusta, cada prop\u00f3sito est\u00e1 encaminado por nuestros reales intereses y necesidades. Una frase que podr\u00eda identificarnos es \u201cvivir el d\u00eda a d\u00eda sin afanes\u201d.<\/p>\n<p>Los dispositivos m\u00f3viles hacen parte de nuestra cotidianidad, sin embargo no est\u00e1n adheridos a nuestras m\u00e1s profundas necesidades. Si est\u00e1n bien y si no tambi\u00e9n, (al menos para la mayor\u00eda), ese d\u00eda a d\u00eda lo construimos a punta de ideas, nuevos proyectos y una comunicaci\u00f3n cercana con los nuestros: amigos y familia.<\/p>\n<p>Digamos que somos una generaci\u00f3n acostumbrada a los cambios tecnol\u00f3gicos, a los que les sacamos mucho provecho en nuestra diversas \u00e1reas, pero hasta ah\u00ed. Eso de estar conectados 24\/7 puede cumplirse en algunos, pero no en todos.<\/p>\n<p>Es navidad y quedan d\u00edas contados para empezar un nuevo a\u00f1o, nuestra identidad nos obliga a estar en ambiente, es decir: compartir f\u00edsicamente con los nuestros, enviar mensajes de Feliz Navidad a trav\u00e9s de nuestros aparatejos inteligentes, publicar e-cards en redes sociales. Puede que las pantallas de los m\u00f3viles nos atrapen por algunos minutos, pero no por el resto de la noche.<\/p>\n<p>Sabemos cu\u00e1ndo quitarnos el chip digital y volver a pon\u00e9rnoslo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Eliana \u00c1lvarez R\u00edos<\/strong><br \/>\n<strong>Directora de Contenidos Web<\/strong><br \/>\n<a href=\"http:\/\/www.colombiadigital.net\/\" target=\"_blank\"><strong>Colombia Digital<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>*Imagen tomada de Getty Images<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las generaciones de los \u00faltimos 20 a\u00f1os han sido marcadas por la explosi\u00f3n digital de las tecnolog\u00edas de la informaci\u00f3n.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/cultura-2\/1165-la-generacion-que-se-quita-y-pone-el-chip\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[483],"tags":[533,405,531,532,445],"class_list":["post-1165","post","type-post","status-publish","format-standard","hentry","category-cultura-2","tag-consumo-digital","tag-dispositivos-moviles","tag-generacion-y","tag-generaciones-digitales","tag-smartphones","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKmq-iN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"predecessor-version":[{"id":1169,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1165\/revisions\/1169"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}