{"id":1032,"date":"2013-04-24T18:54:45","date_gmt":"2013-04-24T23:54:45","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/?p=1032"},"modified":"2013-04-24T18:55:50","modified_gmt":"2013-04-24T23:55:50","slug":"el-significado-de-pararse-en-la-ventana","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/apropiacion\/1032-el-significado-de-pararse-en-la-ventana","title":{"rendered":"El significado de \u00abpararse en la ventana\u00bb"},"content":{"rendered":"<p>En d\u00edas pasados compart\u00ed con mi mam\u00e1 y sus amigas una tarde l\u00fadica en casa. Recordaron viejos amigos, conocidos, maestros, pero sobretodo hablaron de aquellas antiguas amistades con las que desde hac\u00eda mucho tiempo no ten\u00edan ning\u00fan tipo de contacto. Fue entonces, cuando empezamos a rastrearlas por redes sociales. Algunas aparecieron en Facebook, no por tener cuentas propias, sino porque aparec\u00edan en las fotos de sus hijos. Viendo su inter\u00e9s por encontrarse con el pasado, se me ocurri\u00f3 hacer una peque\u00f1a introducci\u00f3n al uso de las TIC (Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones), sin embargo empec\u00e9 a tener problemas con el significado del lenguaje y con la agilidad de esa \u201cpeque\u00f1a clase\u201d.<!--more--><\/p>\n<p>La manipulaci\u00f3n del computador, espec\u00edficamente los recorridos con el mouse de un lugar a otro, fue casi una tarea perdida para algunas de ellas, otras lo lograron con ciertos grados de dificultad. En relaci\u00f3n a los significados del lenguaje no pude esperar m\u00e1s, para ellas <em>\u201cpararse en la ventana\u201d<\/em> se asumi\u00f3 como un desplazamiento f\u00edsico a un lugar de la casa, y no como una ubicaci\u00f3n con el mouse en un espacio de la pantalla del computador. All\u00ed comprend\u00ed que pose\u00eda problemas con las instrucciones dadas.<\/p>\n<p>Para no da\u00f1arles la fiesta y sacar la docente que hay en m\u00ed, decid\u00ed ser el instrumento de acceso a la informaci\u00f3n de familiares y amigos. Ratifiqu\u00e9 una vez m\u00e1s que alfabetizar con base en la motivaci\u00f3n es mucho m\u00e1s f\u00e1cil para quienes nos enamoramos por el tema. Siendo esta (la motivaci\u00f3n) el pilar de cualquier proceso formativo, y es en relaci\u00f3n a ella que debemos pensar los programas educativos.\u00a0<a href=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/04\/Mujeres_apropiaci\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1033\" alt=\"Mujeres_apropiaci\u00f3n\" src=\"http:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/04\/Mujeres_apropiaci\u00f3n-300x210.jpg\" width=\"300\" height=\"210\" srcset=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/04\/Mujeres_apropiaci\u00f3n-300x210.jpg 300w, https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/files\/2013\/04\/Mujeres_apropiaci\u00f3n.jpg 494w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La pregunta que los docentes, tutores o facilitadores debemos resolver permanentemente es \u00bfc\u00f3mo conectar a otras personas en el tema de las TIC?, \u00bfc\u00f3mo acertar con las estrategias pedag\u00f3gicas cuando la motivaci\u00f3n es tan subjetiva y diversa? Aunque este no es el foco de este escrito, vale la pena invitarlos a ustedes lectores a identificar en el uso de las nuevas tecnolog\u00edas \u00bfqu\u00e9 es lo que los ha conectado con la misma?, Y si es una motivaci\u00f3n compartida.<\/p>\n<p>De esta visita, logr\u00e9 conectar a tres personas a un Telecentro donde brindan cursos de alfabetizaci\u00f3n digital como parte de la oferta formativa del Centro de Desarrollo Comunitario ubicado en el barrio.<\/p>\n<p>Despu\u00e9s de todo, aquel encuentro casual result\u00f3 siendo un espacio para redescubrir nuevos saberes y transmitir conocimiento a otras personas interesadas. En t\u00e9rminos de la alfabetizaci\u00f3n digital, ser\u00eda de mucha importancia que los j\u00f3venes, dieran un espacio para hacer la introducci\u00f3n de sus padres al uso de las TIC, disminuir la brecha digital debe ser entendida como un asunto de todos.<\/p>\n<p style=\"text-align: right\"><em>\u00a0*Imagen tomada de Getty Images<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Eugenia Vallejo<br \/>\nCoordinadora de Proyectos Especiales<br \/>\n<a href=\"http:\/\/www.colombiadigital.net\/\">Corporaci\u00f3n Colombia Digital<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00edas pasados compart\u00ed con mi mam\u00e1 y sus amigas una tarde l\u00fadica en casa. Recordaron viejos amigos, conocidos, maestros, pero sobretodo hablaron de aquellas antiguas amistades con las que desde hac\u00eda mucho tiempo no ten\u00edan ning\u00fan tipo de contacto. Fue entonces, cuando empezamos a rastrearlas por redes sociales. Algunas aparecieron en Facebook, no por &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/apropiacion\/1032-el-significado-de-pararse-en-la-ventana\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[3],"tags":[468,57,609,225],"class_list":["post-1032","post","type-post","status-publish","format-standard","hentry","category-apropiacion","tag-alfabetizacion-digital","tag-brecha-digital","tag-educacion","tag-nuevas-tecnologias","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2uKmq-gE","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/comments?post=1032"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1032\/revisions"}],"predecessor-version":[{"id":1035,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/posts\/1032\/revisions\/1035"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/categories?post=1032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/corporacion-colombia-digital\/wp-json\/wp\/v2\/tags?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}