{"id":710,"date":"2023-10-17T16:53:29","date_gmt":"2023-10-17T14:53:29","guid":{"rendered":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/?p=710"},"modified":"2023-10-17T16:53:30","modified_gmt":"2023-10-17T14:53:30","slug":"ninos-intelectuales-los-nuevos-influencers","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2023\/10\/17\/ninos-intelectuales-los-nuevos-influencers\/","title":{"rendered":"Ni\u00f1os intelectuales: los nuevos influencers"},"content":{"rendered":"\n<p>Los \u00abpensadores influencers\u00bb de la red se han erigido como las nuevas figuras de autoridad en la era digital, sin embargo, esta denominaci\u00f3n parece otorgarles un cr\u00e9dito que no han ganado. Como bien se apunta, muchos de ellos parecen ser meros ecos de ideas ajenas, ni\u00f1os intelectuales que se limitan a escuchar y repetir, m\u00e1s que a reflexionar y aportar al discurso colectivo.<\/p>\n\n\n\n<p>En la superficie, el influencer se presenta como un ente poderoso, capaz de mover masas a trav\u00e9s de plataformas como YouTube, Instagram o TikTok, dictando tendencias y moldeando opiniones\u200b. Pero, \u00bfhasta qu\u00e9 punto esta influencia se basa en una reflexi\u00f3n profunda y original? Algunas personas dicen que cuando los influencers en internet hablan con sus seguidores, parece que son amigos charlando, aunque en realidad no lo son. Tambi\u00e9n dicen que a veces, lo que hablan no es muy importante o interesante, pero lo hacen parecer divertido para que m\u00e1s personas les presten atenci\u00f3n.<\/p>\n\n\n\n<p>Muchas veces, el discurso de estos influencers se caracteriza por la demagogia y la emoci\u00f3n m\u00e1s pueril, que busca m\u00e1s el aplauso f\u00e1cil y la validaci\u00f3n en forma de \u00ablikes\u00bb y retuits, que un verdadero enriquecimiento del debate p\u00fablico\u200b\u200b. La superficialidad se convierte en la norma, y la repetici\u00f3n ciega de ideas populares, en la f\u00f3rmula para acumular seguidores y, por ende, poder e influencia.<\/p>\n\n\n\n<p>En la era digital, la autenticidad y la profundidad intelectual parecen estar en retirada, dejando paso a una cultura de la repetici\u00f3n y la superficialidad\u200b.<\/p>\n\n\n\n<p>Esta pseudo-intelectualidad digital promueve una cultura de la pasividad y la conformidad, donde los seguidores se convierten en meros receptores de un discurso que se recicla sin cesar, sin espacio para la cr\u00edtica o la reflexi\u00f3n. La inmediatez y la facilidad de acceso a la informaci\u00f3n que proporciona internet, en lugar de fomentar un pensamiento cr\u00edtico y original, parecen estar contribuyendo a la creaci\u00f3n de una generaci\u00f3n de eco-pensadores que, en lugar de explorar y cuestionar el mundo que les rodea, se contentan con replicar lo que escuchan en sus ecosistemas digitales cerrados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo identificar a estos ni\u00f1os intelectuales?<\/h2>\n\n\n\n<p>En el vasto mar de la cultura digital, navegan numerosos \u00abpensadores influencers\u00bb que, con sus voces resonantes, prometen iluminar mentes y guiar opiniones. Sin embargo, no todos llevan un faro de sabidur\u00eda genuina. Identificar a los verdaderos pensadores de entre la multitud requiere un ojo cr\u00edtico y una oreja discerniente. Aqu\u00ed algunas pautas para navegar estas aguas con precauci\u00f3n:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Profundidad sobre Popularidad:<\/strong> no te dejes llevar por el n\u00famero de seguidores o likes. Busca influencers que ofrezcan reflexiones profundas y bien fundamentadas, no solo aquellos que repiten consignas populares sin an\u00e1lisis cr\u00edtico.<\/li>\n\n\n\n<li><strong>Di\u00e1logo Aut\u00e9ntico:<\/strong> observa si el influencer est\u00e1 dispuesto a entablar di\u00e1logos constructivos con sus seguidores y otros pensadores, o si simplemente se queda en la superficie con respuestas prefabricadas.<\/li>\n\n\n\n<li><strong>Transparencia:<\/strong> un verdadero pensador es transparente sobre sus intenciones, las fuentes de su informaci\u00f3n y est\u00e1 dispuesto a admitir y corregir errores.<\/li>\n\n\n\n<li><strong>Diversidad de Perspectivas:<\/strong> busca influencers que explore diferentes puntos de vista y no se encierre en una sola narrativa. La diversidad en el discurso refleja una mente abierta y una voluntad de explorar la verdad desde m\u00faltiples \u00e1ngulos.<\/li>\n\n\n\n<li><strong>Educaci\u00f3n Continua:<\/strong> un influencer que valora el conocimiento estar\u00e1 en una b\u00fasqueda constante de aprendizaje y crecimiento personal. Observa si comparten recursos educativos, libros o experiencias que les hayan desafiado y ayudado a evolucionar.<\/li>\n\n\n\n<li><strong>Valor Agregado:<\/strong> pregunta, \u00bfqu\u00e9 valor est\u00e1 aportando este influencer a mi comprensi\u00f3n del mundo? Si la respuesta es poco o nada, tal vez sea el momento de buscar mentes m\u00e1s enriquecedoras a quienes seguir.<\/li>\n<\/ol>\n\n\n\n<p>El discernimiento en la elecci\u00f3n de a qui\u00e9n seguir en la esfera digital puede ayudar a cultivar un ambiente en l\u00ednea m\u00e1s enriquecedor y a fomentar un discurso m\u00e1s profundo y significativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00abpensadores influencers\u00bb de la red se han erigido como las nuevas figuras de autoridad en la era digital, sin embargo, esta denominaci\u00f3n parece otorgarles un cr\u00e9dito que no han ganado. Como bien se apunta, muchos de ellos parecen ser meros ecos de ideas ajenas, ni\u00f1os intelectuales que se limitan a escuchar y repetir, m\u00e1s &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2023\/10\/17\/ninos-intelectuales-los-nuevos-influencers\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-710","post","type-post","status-publish","format-standard","hentry","category-opinion","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"predecessor-version":[{"id":712,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/710\/revisions\/712"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/tags?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}