{"id":634,"date":"2021-09-21T01:43:21","date_gmt":"2021-09-20T23:43:21","guid":{"rendered":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/?p=634"},"modified":"2021-09-21T01:43:22","modified_gmt":"2021-09-20T23:43:22","slug":"la-inseguridad-en-bucaramanga-es-un-chiste-de-mal-gusto","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2021\/09\/21\/la-inseguridad-en-bucaramanga-es-un-chiste-de-mal-gusto\/","title":{"rendered":"La inseguridad en Bucaramanga es un chiste de mal gusto"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0070\/0566\/7387\/products\/bootfront_1024x1024@2x.jpg?v=1586146093\" alt=\"La inseguridad en Bucaramanga es un chiste de mal gusto.\" width=\"838\" height=\"601\" \/><\/figure>\n\n\n\n<p>Me encontr\u00e9 a don Alonso lustrando botas cerca al parque de las Mejoras P\u00fablicas, o a lo que queda de ese parque. <\/p>\n\n\n\n<p>Con 71 a\u00f1os, Alonso, se gana la vida desde hace 13 a\u00f1os en los diferentes parques de la ciudad haciendo lo que mejor se le da: lustrar zapatos y poner conversa. La clave: bet\u00fan de calidad y clientes fieles.<\/p>\n\n\n\n<p>No est\u00e1 de m\u00e1s anotar que pocos, como los lustrabotas, conocen los detalles vulgares de la Bucaramanga oculta. Por eso comenzamos a hablar de la inseguridad de la ciudad y c\u00f3mo esto le ha afectado su trabajo.<\/p>\n\n\n\n<p>\u00abAntes de la pandemia, pod\u00eda hacerme unos 5 o 6 clientes casuales en un par de horas. Es relativo. Hoy en la ma\u00f1ana no trabaj\u00e9 mucho, a lo mejor a la tarde ya no pasa nada\u00bb, pronostica.<\/p>\n\n\n\n<p>\u00abA eso s\u00famele las ratas\u00bb, se queja. \u00abYa la gente tiene miedo de salir a caminar con los zapatos limpios.\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A don Alonso le fastidia que no le hablen claro<\/h2>\n\n\n\n<p>Para hablarle a don Alonso sobre seguridad no tuve que emplear la jerga tecnocr\u00e1tica que suelen utilizar los expertos del tema, solo tuve que decir \u00abA esa gente le hace falta <em>juete <\/em>para que aprendan\u00bb. Obvio, yo soy muy ingenuo y no esperaba que me respondiera con un \u00abEso ya no sirve, esa gente ya no se regenera, solo sirven para pudrirse en una c\u00e1rcel\u00bb.<\/p>\n\n\n\n<p>Le insist\u00ed en que las personas necesitan una segunda oportunidad y que los programas de resocializaci\u00f3n pueden convertir en ciudadano al delincuente, pero el viejo me contest\u00f3: \u00abEsa gente solo entiende a las patadas, a punta de plomo, desgastarse tratando de ense\u00f1arle modales a esos carro\u00f1eros solo es botar la plata, pero no falta el estudiante bobo que cree todo lo que le ense\u00f1an en la universidad\u00bb.<\/p>\n\n\n\n<p>Yo me qued\u00e9 callado.<\/p>\n\n\n\n<p>Pero como \u00e9l hay muchos. Por la calle va gente que ya no cree en la sofisticaci\u00f3n para acabar con el <em>hampa policausal<\/em>, solo quiere salir a trabajar y no preocuparse por las motos que le pasan cerca. Si mucho le creen al que habla sin tapujos, al que a punta de <em>juete <\/em>quiere arreglar la sociedad&#8230;<\/p>\n\n\n\n<p>Al final y ya para despedirme le dije a don Alonso que es mejor la seguridad que la polic\u00eda, me mir\u00f3 a los ojos mientras levantaba una ceja y dejaba escapar una leve sonrisa esquinera.<\/p>\n\n\n\n<p>Pagu\u00e9 10mil pesos y me met\u00ed r\u00e1pido a una tienda. Uno ya no puede andar por ah\u00ed con los zapatos embolados porque lo van fichando de una.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me encontr\u00e9 a don Alonso lustrando botas cerca al parque de las Mejoras P\u00fablicas, o a lo que queda de ese parque. Con 71 a\u00f1os, Alonso, se gana la vida desde hace 13 a\u00f1os en los diferentes parques de la ciudad haciendo lo que mejor se le da: lustrar zapatos y poner conversa. La clave: &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2021\/09\/21\/la-inseguridad-en-bucaramanga-es-un-chiste-de-mal-gusto\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-634","post","type-post","status-publish","format-standard","hentry","category-ficcion-historica","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/comments?post=634"}],"version-history":[{"count":3,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/634\/revisions"}],"predecessor-version":[{"id":637,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/634\/revisions\/637"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media?parent=634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/categories?post=634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/tags?post=634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}