{"id":599,"date":"2021-04-17T21:02:43","date_gmt":"2021-04-17T19:02:43","guid":{"rendered":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/?p=599"},"modified":"2021-04-18T19:23:24","modified_gmt":"2021-04-18T17:23:24","slug":"mano-negra-bucaramanga","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2021\/04\/17\/mano-negra-bucaramanga\/","title":{"rendered":"El fantasma de la Mano Negra recorre Bucaramanga"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abLo correcto es quitar una vida humana en estos casos porque aqu\u00ed los procesos legales tardan mucho y el narcotraficante o el asesino que podamos atrapar como polic\u00edas puede quedar en libertad al d\u00eda siguiente y volver a las calles a matar y traficar con drogas de nuevo, as\u00ed que es mucho mejor que nos encarguemos de estos bandidos, que los matemos y resolvamos el problema as\u00ed\u00bb.<\/p><cite>Brasil, 2013<\/cite><\/blockquote>\n\n\n\n<p>Lo anterior fue mencionado en 2013 por un polic\u00eda durante <a href=\"https:\/\/www.independent.co.uk\/news\/world\/americas\/death-undesirables-brazil-s-murder-capital-1685214.html\" target=\"_blank\" rel=\"noreferrer noopener\">una entrevista para el peri\u00f3dico The Independent de UK<\/a> y casi una d\u00e9cada despu\u00e9s, se pueden escuchar comentarios similares entre los bumangueses que usan redes sociales. Lo curioso es que en la ciudad a\u00fan se recuerda con temor la <a href=\"https:\/\/www.vanguardia.com\/judicial\/lo-que-los-bumangueses-no-recuerdan-de-la-mano-negra-DFVL377730\" target=\"_blank\" rel=\"noreferrer noopener\">ola de masacres realizada por la Mano Negra<\/a> hace un par de d\u00e9cadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los superh\u00e9roes en Bucaramanga no deber\u00edan existir<\/h2>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"477\" src=\"http:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2021\/04\/mano-negra-en-bucaramanga.jpg\" alt=\"mano negra en bucaramanga\" class=\"wp-image-603\" srcset=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2021\/04\/mano-negra-en-bucaramanga.jpg 716w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2021\/04\/mano-negra-en-bucaramanga-300x200.jpg 300w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><figcaption>(Foto: Marco Valencia\/VANGUARDIA LIBERAL) <\/figcaption><\/figure>\n\n\n\n<p>No existe el Batman o Superman colombiano, eso es solo de los gringos. Sin embargo, el fen\u00f3meno de \u00abvigilantismo\u00bb se materializa a trav\u00e9s de \u00abkilling squads\u00bb a los que se les conoce de forma popular como \u00abMano Negra\u00bb.<\/p>\n\n\n\n<p>Definido como \u00abactos premeditados de fuerza o amenaza de fuerza por parte de ciudadanos aut\u00f3nomos\u00bb, el vigilantismo o \u00abmano negrismo\u00bb (como lo llamar\u00e9 de ahora en adelante) es una actividad que tiene lugar fuera de las instituciones formales, pero que a veces es apoyada t\u00e1citamente o perpetrada por actores institucionales <strong>(\u00bfles suena las Convivir?)<\/strong>.<\/p>\n\n\n\n<p>En la \u00abCiudad de los Parques\u00bb es com\u00fan escuchar con m\u00e1s frecuencia un apoyo sin tapujos al regreso de la Mano Negra cuando se incrementan los casos atracos masivos. <strong>Es incierto para m\u00ed, el justificar con datos, que el exponencial crecimiento de la diversidad cultural mezclada con<\/strong> <a href=\"https:\/\/www.vanguardia.com\/politica\/alcalde-de-bucaramanga-juan-carlos-cardenas-el-tercero-en-imagen-favorable-en-el-pais-guarumo-MD3489970\" target=\"_blank\" rel=\"noreferrer noopener\">el 55% <\/a> de popularidad del gobierno local y el impacto de la pandemia, tambi\u00e9n han jugado un papel fundamental en el aumento de la popularidad de este tipo de organizaciones parapoliciales entre los bumangueses. Y aunque los vigilantes a veces resuelven problemas cuando los Estados no pueden, el \u00abMano Negrismo\u00bb es propenso al oportunismo y puede generar violencia, corrupci\u00f3n y alteraci\u00f3n social.<\/p>\n\n\n\n<p>Pareciera obvio que los vigilantes suelen actuar en Estados d\u00e9biles que carecen de capacidad para proporcionar seguridad y servicios a los ciudadanos, no se debe olvidar que el vigilantismo tambi\u00e9n puede surgir en Estados fuertes, especialmente en zonas que se est\u00e1n transformando cultural o institucionalmente. Colombia es un ejemplo de Estado que no se percibe como fuerte y con eso estoy comenzando a dudar del gobierno local&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Peligros de la Mano Negra<\/h2>\n\n\n\n<p>En Internet se ven historias de personas que han localizado y recuperado sus propios celulares mediante un software de rastreo o que simplemente han matado a un asaltante mientras ayudaban a la v\u00edctima. Estas personas suelen recibir muchos elogios en las redes sociales por lo que es una actividad seriamente peligrosa. Sin embargo, lo que no se suele o\u00edr es el peligro que entra\u00f1a esa actividad.<\/p>\n\n\n\n<p>Es f\u00e1cil ver lo r\u00e1pido que la situaci\u00f3n podr\u00eda convertirse en un ba\u00f1o de sangre. Si uno de estos extremistas (en su mayor\u00eda no entrenados) y fuertemente armados percibe una amenaza, tal vez en la oscuridad confunden a un repartidor de Rappi con un criminal y abren fuego contra una multitud densamente poblada, \u00bfcu\u00e1ntas vidas inocentes podr\u00edan perderse?<\/p>\n\n\n\n<p><strong>Aunque no hay reportes de una resurecci\u00f3n de la Mano Negra en Bucaramanga, no podemos tolerar su aparici\u00f3n apenas se presente en la ciudad<\/strong>. No podemos permitir que bandas armadas de civiles hagan cumplir nuestras leyes locales. De hecho, el vigilantismo es responsable de algunos de los actos m\u00e1s oscuros y malvados de nuestra historia. No hace falta mirar m\u00e1s all\u00e1 de las masacres de los Paramilitares para entender a d\u00f3nde conduce la tolerancia hacia la \u00abMano Negra\u00bb.<\/p>\n\n\n\n<p>La aplicaci\u00f3n de la seguridad pertenece \u00fanicamente a las manos de profesionales capacitados en la aplicaci\u00f3n de la ley (Polic\u00eda), no a vigilantes armados. Entonces debemos preguntarnos, \u00bfqu\u00e9 est\u00e1n haciendo la Alcald\u00eda y la Polic\u00eda para prevenir o mitigar la delincuencia en Bucaramanga?<\/p>\n\n\n\n<p><strong>Quiero seguir caminando por La 33 como antes: sin miedo a encontrarme con la muerte.<\/strong><\/p>\n\n\n\n<p><span style=\"color:#999b9c\" class=\"has-inline-color\">Para quienes est\u00e9n interesados en leer m\u00e1s sobre el <em>\u00abMano Negrismo\u00bb<\/em>, pueden<\/span> <a href=\"https:\/\/library.oapen.org\/bitstream\/id\/eda97d10-51d2-4cd4-a8ad-99cfd5117348\/9781138493803_text.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">leer este libro<\/a>. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLo correcto es quitar una vida humana en estos casos porque aqu\u00ed los procesos legales tardan mucho y el narcotraficante o el asesino que podamos atrapar como polic\u00edas puede quedar en libertad al d\u00eda siguiente y volver a las calles a matar y traficar con drogas de nuevo, as\u00ed que es mucho mejor que nos &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2021\/04\/17\/mano-negra-bucaramanga\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":38,"featured_media":603,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2021\/04\/mano-negra-en-bucaramanga.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":7,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":609,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/599\/revisions\/609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media\/603"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}