{"id":247,"date":"2020-06-18T04:25:14","date_gmt":"2020-06-18T02:25:14","guid":{"rendered":"http:\/\/blogs.vanguardia.com\/caminando-por-la-33\/?p=247"},"modified":"2020-06-18T05:01:50","modified_gmt":"2020-06-18T03:01:50","slug":"luis-a-calvo-y-el-diablo-en-la-botella","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2020\/06\/18\/luis-a-calvo-y-el-diablo-en-la-botella\/","title":{"rendered":"Lu\u00eds A. Calvo y el diablo en la botella"},"content":{"rendered":"\n<p>El padre de la teor\u00eda de la gravedad, Isaac Newton; los m\u00fasicos Mozart y Beethoven y hasta el propio Einstein padecieron trastorno bipolar. El gran genio de la pintura Van Gogh sufri\u00f3 de psicosis; e incluso Darwin, autor de la teor\u00eda de la evoluci\u00f3n, ten\u00eda trastorno del p\u00e1nico. \u00bfExiste alguna relaci\u00f3n entre las patolog\u00edas de estos genios y su talento? Aunque <a aria-label=\"es algo probable (opens in a new tab)\" href=\"https:\/\/www.clarin.com\/sociedad\/confirman-relacion-grandes-genios-locura_0_SJi-9V92DQg.html\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"aioseop-link\">es algo probable<\/a>, no convence a los esc\u00e9pticos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion-2-1.png\" alt=\"\" class=\"wp-image-293\" width=\"222\" height=\"239\" srcset=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion-2-1.png 414w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion-2-1-278x300.png 278w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<p>No hay muchos lazaretos hoy en d\u00eda, pero en el pasado eran muy comunes. Dondequiera que se busque sobre la lepra, se encontrar\u00e1 que ha sido considerada castigo divino debido a una conducta reprochable. Sin duda, la lepra es una enfermedad hist\u00f3rica envuelta en mitos y leyendas que se rehusan a morir.<\/p>\n\n\n\n<p>Estas creencias son las que hacen que muchos leprosarios se mantengan en pie, tal es el caso del de <a aria-label=\"Kalaupapa en Hawaii (opens in a new tab)\" href=\"https:\/\/www.bbc.com\/mundo\/noticias-37253322\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"aioseop-link\">Kalaupapa en Hawaii<\/a> y el de otros ubicados en India y <a aria-label=\"Jap\u00f3n (opens in a new tab)\" href=\"https:\/\/www.elperiodico.com\/es\/internacional\/20190712\/japon-pide-perdon-discriminar-durante-decadas-leprosos-7550718\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"aioseop-link\">Jap\u00f3n<\/a>. Aunque la lepra ya no representa un peligro para la salud p\u00fablica, a\u00fan sigue teniendo mala reputaci\u00f3n en la sociedad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Esta es la historia sobre c\u00f3mo Luis A. Calvo se contagi\u00f3:<\/strong><\/h2>\n\n\n\n<p>Los hombres siempre han sentido fascinaci\u00f3n por los atajos y por qui\u00e9nes les puedan brindar ayuda para llevar a cabo m\u00e1s r\u00e1pido su cometido.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo es posible que un ni\u00f1o de escasos recursos, con un limitado talento musical, se haya convertido en una figura p\u00fablica en la Colombia de 1920?<\/p>\n\n\n\n<p>Esta pregunta surge despu\u00e9s de escuchar una conversaci\u00f3n sigilosa, en uno de los antros m\u00e1s discretos de Bucaramanga. Esto fue lo que descubr\u00ed:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El peque\u00f1o empuj\u00f3n<\/h3>\n\n\n\n<p class=\"has-drop-cap\">Calvo fue un hombre que vivi\u00f3 en Colombia entre 1882 y 1945, y que al margen de los acontecimientos que marcaron el rumbo del pa\u00eds en esos a\u00f1os, <a aria-label=\"se dedic\u00f3 a la m\u00fasica (opens in a new tab)\" href=\"http:\/\/www.uis.edu.co\/webUIS\/es\/mediosComunicacion\/revistaSantander\/revista1\/luisACalvo.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"aioseop-link\">se dedic\u00f3 a la m\u00fasica<\/a>.<\/p>\n\n\n\n<p>No se explica a simple vista el hecho de que un m\u00fasico no profesional, que no fue un referente para la historia de la musica, haya despertado tanta simpat\u00eda y euforia durante su trayector\u00eda musical. Calvo fue un compositor de formas sencillas y peque\u00f1as, tal cual lo expresa el historiador <a rel=\"noreferrer noopener\" href=\"http:\/\/bdigital.unal.edu.co\/10793\/\" target=\"_blank\">Daniel Ospina<\/a>.<\/p>\n\n\n\n<p>Luis sab\u00eda que su falta de t\u00e9cnica necesitaba un peque\u00f1o empuj\u00f3n para poder sobresalir y aparecer en los libros de historia, lo que no sab\u00eda era el alto costo que tendr\u00eda que pagar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sus a\u00f1os maravillosos en Bogot\u00e1 junto a los Panidas<\/h3>\n\n\n\n<p>La Constituci\u00f3n antifederalista, conservadora y unitaria de 1886, sumada a una fuerte influencia de la iglesia cat\u00f3lica y a la separaci\u00f3n de Panam\u00e1, tuvo un gran impacto en la juventud colombiana, ya que aument\u00f3 su inconformidad y esto incentiv\u00f3 la creaci\u00f3n de muchos movimientos literarios y art\u00edsticos; entre ellos el de los Panidas, organizaci\u00f3n a la cual perteneci\u00f3 Le\u00f3n de Greiff.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Los-Panidas-Buhos.gif\" alt=\"\" class=\"wp-image-294\" width=\"589\" height=\"336\" \/><figcaption><strong>La tertulia del \u00abNegro\u00bb<br>Personajes: Jes\u00fas Restrepo Rivera, Le\u00f3n de Greiff, Ciro Mend\u00eda, El Negro Cano, Efe G\u00f3mez, Alfonso Castro.<br>Ilustraci\u00f3n de Longas.<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p>Aunque los Panidas hab\u00edan nacido en Medell\u00edn, en 1916 algunos de ellos se <a rel=\"noreferrer noopener\" href=\"https:\/\/www.banrepcultural.org\/biblioteca-virtual\/credencial-historia\/numero-70\/los-panidas-de-medellin\" target=\"_blank\">trasladaron r\u00e1pidamente a Bogot\u00e1<\/a> cargando un equipaje ligero, ya que esta organizaci\u00f3n de intelectuales belicosos ten\u00edan como regla el tener un estilo de vida n\u00f3mada y similar al de la sociedad de la <a rel=\"noreferrer noopener\" href=\"http:\/\/lapiedradesisifo.com\/2014\/09\/23\/historia-abreviada-de-la-literatura-port%C3%A1til\/\" target=\"_blank\">Literatura Port\u00e1til<\/a>.<\/p>\n\n\n\n<p>Ya instalados en Bogot\u00e1, decidieron seguir con su rutina en uno de los caf\u00e9s m\u00e1s conocidos de la \u00e9poca: el <a rel=\"noreferrer noopener\" href=\"https:\/\/esferapublica.org\/nfblog\/los-cafes-que-murieron-el-9-de-abril\/\" target=\"_blank\">Caf\u00e9 La Gran V\u00eda<\/a>. All\u00ed conocer\u00edan a Luis. A. Calvo, un tipo de aspecto algo tosco, ingenuo y con buenas intenciones, \u00e1vido de una aventura citadina completa.<\/p>\n\n\n\n<p>En el trascurso de un poco m\u00e1s de diez a\u00f1os, Calvo pas\u00f3 de ser un migrante desconocido en Bogot\u00e1, con profundas carencias econ\u00f3micas una educaci\u00f3n musical incipiente y remotos prospectos de \u00e9xito, a ser un m\u00fasico medianamente formado en lo acad\u00e9mico, pero suficientemente reconocido como int\u00e9rprete y compositor. En pocas palabras, entre 1907 y 1916 se convirti\u00f3 en un personaje famoso en esta ciudad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">No contaba con la parla del caricaturista Ricardo Rend\u00f3n<\/h3>\n\n\n\n<p>Conocido nacionalmente por ser el creador de la c\u00e9lebre ilustraci\u00f3n de la marca de cigarrillos Pielroja, Ricardo Rend\u00f3n fue un caricaturista y retratista implacable con gran capacidad de abstracci\u00f3n. Tal vez esa capacidad anal\u00edtica fue lo que atrajo a Luis A. Calvo, ya que fue Rend\u00f3n quien le convencer\u00eda de suicidarse.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Las habilidades de Rend\u00f3n para convencer gente<\/h4>\n\n\n\n<p>Al mejor estilo de Charles Manson, el caricaturista ten\u00eda una filosof\u00eda de encontrar personas con carencias, para con ellas entablar un culto al rededor del suicidio. Su habilidad para leer gente y transformarse en una persona agradable a su interlocutor, le dio las herramientas necesarias para convencer a Calvo: \u00e9l era el especimen perfecto para empezar sus actividades suicidas en Bogot\u00e1. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Ricardo-Rendon-jpg.jpg\" alt=\"\" class=\"wp-image-295\" width=\"587\" height=\"415\" srcset=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Ricardo-Rendon-jpg.jpg 512w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Ricardo-Rendon-jpg-300x212.jpg 300w\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" \/><\/figure>\n\n\n\n<p>Aunque Rend\u00f3n se mat\u00f3 a\u00f1os despu\u00e9s de este primer encuentro con Calvo, el da\u00f1o ya estaba hecho y el m\u00fasico encontrar\u00eda su fat\u00eddico destino m\u00e1s temprano de lo esperado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El diablo en la botella<\/h3>\n\n\n\n<p>A\u00f1os antes de suicidarse, cuando apenas hab\u00eda llegado a Bogot\u00e1, Luis supo que deb\u00eda encontrar una ventaja frente a sus rivales musicales. El tipo de ventaja que buscaba no se la pod\u00eda brindar ning\u00fan incipiente conservatorio de la \u00e9poca, ni siquiera el mism\u00edsimo Guillermo Uribe Holgu\u00edn pod\u00eda hacerlo. El esp\u00edritu guane que resid\u00eda en \u00e9l, lo empuj\u00f3 a buscar la ayuda de lo divino entre lo m\u00e1s rec\u00f3ndito de la naciente fauna bogotana.<\/p>\n\n\n\n<p>Luis decide ir a la calle 12 con carrera 10: un lugar donde el comercio informal se mezcla con la brujer\u00eda. Parece que un artefacto lo estaba esperando: a los minutos de llegar y entre carpa y carpa, patea sin querer una botella de panza redonda con cuello muy largo, el cristal era de un color blanco como el de la leche, con cambiantes destellos irisados en su textura. En el interior hab\u00eda algo que se mov\u00eda confusamente, algo as\u00ed como humo y un trozo de papel.<\/p>\n\n\n\n<p>Al recoger la botella, se dio cuenta que alguien lo miraba a trav\u00e9s de una cortina trasl\u00facida desde uno de los asentamientos de esta calle. Era el vendedor de esa botella: un hombre maduro, rapado y de barba blanca. Este haitiano sol\u00eda dejar los objetos que quer\u00eda vender, a su suerte en los pasajes cercanos a su carpa, para que la gente los encontrara y as\u00ed convencerles de que el destino los hab\u00eda tra\u00eddo hasta ese lugar.<\/p>\n\n\n\n<p>El negro le hizo un gesto a Luis para que entrara en el local improvisado dentro de la carpa y le pregunt\u00f3: \u00ab\u00bfLe gustar\u00eda tener fama en esta vida?\u00bb<\/p>\n\n\n\n<p>Suspirando, Luis asinti\u00f3 con la cabeza a lo que el bokor le hizo una segunda pregunta: \u00abTiene alg\u00fan dinero, \u00bfcierto?\u00bb, Luis asinti\u00f3 de nuevo con la cabeza.<\/p>\n\n\n\n<p>Calvo sab\u00eda lo que estaba buscando, le pag\u00f3 una \u00ednfima cantidad de centavos por la botella y march\u00f3 antes de que el brujo le describiera casi todas las particularidades de la botella.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El argumento fatal del caricaturista<\/h3>\n\n\n\n<p>Volviendo a Ricardo Rend\u00f3n, se sabe que para inicios de marzo de 1916, ofreci\u00f3 una gran fiesta donde uno de los invitados predilectos fue Luis A. Calvo.<\/p>\n\n\n\n<p>Un sinf\u00edn de champagne, coristas, bailarinas y contrabandistas; uso de trajes formales y literarios, m\u00e1scaras y mujeres desnudas&#8230; nunca se sabe a qui\u00e9nes encontrar\u00e1s en las fiestas: podr\u00eda ser un viejo enemigo, un viejo amigo o un viejo amigo que se ha convertido en un enemigo. Podr\u00edas encontrarte con un ex-amante, con tu pr\u00f3ximo amante o te puede seducir la muerte, tal cual le pas\u00f3 al joven m\u00fasico, ya que el caricaturista no cesaba de fascinar a Calvo sobre la belleza del suicidio por encima de cualquier superstici\u00f3n. Morir joven era todo lo que se necesitaba para ser recordado por siempre en la historia. Estas palabras retumbaron en la cabeza mareada del m\u00fasico.<\/p>\n\n\n\n<p>No se saben todos los detalles, cavilaciones y ramas por las cuales ambos recorrieron la noche en una tertulia magn\u00edfica, pero s\u00ed que el \u00fanico resultado de este aquelarre fue un Luis embriagado con alcohol y envenenado con una sobredosis de coca\u00edna. <strong>El hijo predilecto de Santa F\u00e9 de G\u00e1mbita muri\u00f3 esa madrugada, pero nadie se enter\u00f3&#8230; ni \u00e9l mismo.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El despertar de un ruise\u00f1or: el nuevo hogar de Calvo<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion.png\" alt=\"\u201cLa resurrecci\u00f3n de Luis A. Calvo\u201d (1932) Art\u00edculo del peri\u00f3dico Mundo al D\u00eda del 20 de\nmayo de 1932. Foto Sergio Ospina\" class=\"wp-image-291\" width=\"280\" height=\"449\" srcset=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion.png 447w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion-187x300.png 187w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><figcaption>\u201cLa resurrecci\u00f3n de Luis A. Calvo\u201d (1932) Art\u00edculo del peri\u00f3dico Mundo al D\u00eda del 20 de<br>mayo de 1932. Foto Sergio Ospina\u201c<\/figcaption><\/figure><\/div>\n\n\n\n<p>Para 1916, Luis ya ten\u00eda resuelta una parte considerable de su <a href=\"http:\/\/bdigital.unal.edu.co\/65249\/1\/52162-255180-1-SM.pdf\" target=\"_blank\" aria-label=\"legado est\u00e9tico (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"aioseop-link\">legado est\u00e9tico<\/a>, era toda una celebridad distinguida y pod\u00eda participar con suficiente alborozo de varias de las ofertas que en materia de recreaci\u00f3n le ofrec\u00eda una a\u00fan polvorienta ciudad de Bogot\u00e1. Las condiciones de salubridad capitalinas no eran las mejores: una gran parte de los establecimientos y residencias a\u00fan eran muladares, ambiente prop\u00edcio para enfermedades como la lepra.<\/p>\n\n\n\n<p>Los s\u00edntomas inc\u00f3modos de la enfermedad de Hansen, como tambi\u00e9n se le conoce a la lepra, empezaron a manifestarse en su cuerpo. Se lleg\u00f3 a pensar, primeramente, que se trataba de las consecuencias de llevar una vida no tan apegada a las directrices de la Regeneraci\u00f3n.<\/p>\n\n\n\n<p>No cab\u00eda duda, era lepra. La noticia fue devastadora para todos sus allegados. Las carencias materiales y las adversas condiciones habitacionales sufridas por Calvo durante sus primeros a\u00f1os en la capital, le pasaron una costosa cuenta de cobro. La \u00faltima quincena de marzo fue dolorosa para Calvo: su vida se fue al traste. D\u00edas despu\u00e9s, se traslad\u00f3 al campo de concentraci\u00f3n para leprosos m\u00e1s famoso de Colombia: Agua de Dios, un caser\u00edo de tierra caliente en Cundinamarca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfRealmente fue lepra?<\/h3>\n\n\n\n<p>\u00bfPor qu\u00e9 don Luis A. Calvo no sufri\u00f3 de las burlas y persecuciones a las que estaban habituadas las personas se\u00f1aladas de tener lepra? \u00bfQu\u00e9 ten\u00eda Calvo para ser diferente?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ten\u00eda una botella<\/h4>\n\n\n\n<p>Cuando Luis sali\u00f3 afanado de la carpa de la calle12 con carrera 10,  sin escuchar minuciosamente al bokor, el brujo vud\u00fa, no se imagin\u00f3 que realmente esa baratija le saldr\u00eda muy cara. La botella tiene vida y legislaci\u00f3n propia, se gobierna a s\u00ed misma.<\/p>\n\n\n\n<p>Esa botella es conocida por albergar una entidad vud\u00fa. El historiador Robert Louis Stevenson detalla claramente en su magistral obra \u00ab<a aria-label=\"El diablo de la botella (opens in a new tab)\" href=\"http:\/\/www.ataun.eus\/BIBLIOTECAGRATUITA\/Cl%C3%A1sicos%20en%20Espa%C3%B1ol\/Robert%20Louise%20Stevenson\/El%20diablo%20de%20la%20botella.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"aioseop-link\">El diablo de la botella<\/a>\u00ab, todas las peculiaridades de este artefacto maldito:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Una entidad divina vive en ella. Cuando un hombre compra esta botella el diablo o el Loa Sobo que vive dentro, se pone a su servicio; todo lo que esa persona desee: amor, fama, dinero, talento, ser\u00e1 suyo con s\u00f3lo pedirlo. Napole\u00f3n tuvo esta botella, y gracias a su virtud lleg\u00f3 a ser el rey del mundo; pero la vendi\u00f3 al final y fracas\u00f3. El capit\u00e1n Cook tambi\u00e9n la tuvo y por ella descubri\u00f3 tantas islas; pero tambi\u00e9n \u00e9l la vendi\u00f3 y por eso lo asesinaron en Hawaii. Porque al vender la botella desaparecen el poder y la protecci\u00f3n; y a no ser que un hombre est\u00e9 contento con lo que tiene, acaba por sucederle algo.<\/p><cite>Robert Louis Stevenson<\/cite><\/blockquote>\n\n\n\n<p>Pero hab\u00eda algo m\u00e1s&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Hay un inconveniente con el Loa de la botella; si un hombre muere antes de venderla, volver\u00e1 a la vida con una inmensa maldici\u00f3n en su cuerpo.<\/p><cite>Robert Louis Stevenson<\/cite><\/blockquote>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Sin duda alguna, la muerte prematura de Calvo precipit\u00f3 la maldici\u00f3n de la divinidad vud\u00fa encerrada en la botella.<\/p>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\">Calvo muri\u00f3 en Juan de Dios, pero nunca se encontr\u00f3 su cuerpo. Los lugare\u00f1os dicen que no soport\u00f3 la agon\u00eda de la lepra y decidi\u00f3 matarse. Lo que no sab\u00edan los habitantes es que Calvo ya hab\u00eda muerto muchos a\u00f1os atr\u00e1s y que realmente no ten\u00eda Lepra; Luis A. Calvo sigue vivo, \u00a1es un zombie!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"398\" src=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente-1024x398.jpg\" alt=\"\" class=\"wp-image-296\" srcset=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente-1024x398.jpg 1024w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente-300x117.jpg 300w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente-768x299.jpg 768w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente-1536x597.jpg 1536w, https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-es-un-muerto-viviente.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El padre de la teor\u00eda de la gravedad, Isaac Newton; los m\u00fasicos Mozart y Beethoven y hasta el propio Einstein padecieron trastorno bipolar. El gran genio de la pintura Van Gogh sufri\u00f3 de psicosis; e incluso Darwin, autor de la teor\u00eda de la evoluci\u00f3n, ten\u00eda trastorno del p\u00e1nico. \u00bfExiste alguna relaci\u00f3n entre las patolog\u00edas de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/2020\/06\/18\/luis-a-calvo-y-el-diablo-en-la-botella\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":38,"featured_media":291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ficcion-historica","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/files\/2020\/06\/Luis-A-Calvo-Resureccion.png","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":48,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/247\/revisions"}],"predecessor-version":[{"id":302,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/posts\/247\/revisions\/302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media\/291"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/media?parent=247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/categories?post=247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/caminando-por-la-33\/wp-json\/wp\/v2\/tags?post=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}