{"id":44,"name":"alcompasdejuan","url":"","description":"","link":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/author\/alcompasdejuan\/","slug":"alcompasdejuan","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/users\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/users"}]}}