{"id":79,"date":"2021-06-11T17:17:46","date_gmt":"2021-06-11T17:17:46","guid":{"rendered":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/?p=79"},"modified":"2021-06-11T17:17:47","modified_gmt":"2021-06-11T17:17:47","slug":"hay-que-sacar-al-diablo","status":"publish","type":"post","link":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/2021\/06\/11\/hay-que-sacar-al-diablo\/","title":{"rendered":"Hay que sacar al diablo"},"content":{"rendered":"\n<p>A mes y medio del inicio del Paro Nacional,  he querido escribir sobre Hay que sacar al diablo, bambuco escrito en 1989, pero con un mensaje que se mantiene actual.<\/p>\n\n\n\n<p><strong>Eugenio Arellano<\/strong> es el nombre del compositor de esta canci\u00f3n que se estren\u00f3 en el <strong><em>\u201cPrimer encuentro de la M\u00fasica Colombiana\u201d<\/em><\/strong> celebrado en la ciudad de Bogot\u00e1 un 13 de diciembre de 1989.<\/p>\n\n\n\n<p>Este fue un a\u00f1o tr\u00e1gico, uno de los muchos de nuestra historia. <strong>Luis Carlos Gal\u00e1n Sarmiento<\/strong> fue asesinado el 18 de agosto de 1989, la violencia desatada por <strong>Pablo Escobar<\/strong> llenaba de miedo a todos los colombianos que ve\u00edan como desde principios de ese a\u00f1o ocurr\u00edan masacres como la de <strong>La Rochela<\/strong> en el municipio de <strong>Simacota<\/strong> en Santander el 18 de enero, hasta la suspensi\u00f3n del torneo de futbol por el <strong>asesinato de un \u00e1rbitro<\/strong> a manos de la mafia el 15 de noviembre. La <a href=\"https:\/\/www.bbc.com\/mundo\/noticias-america-latina-47742991\">BBC tiene un muy buen art\u00edculo<\/a> en el que explican el contexto pol\u00edtico y social que el pa\u00eds viv\u00eda cuando se estren\u00f3 el bambuco sobre el que aqu\u00ed escribo.<\/p>\n\n\n\n<p>La historia que relata <strong>Hay que sacar al diablo<\/strong> es la del dolor de un colombiano que no ve cambios en su pa\u00eds, que las cosas en vez de mejorar, <strong>andan de mal en peor<\/strong> y nos invita a que <strong>no nos callemos teniendo voz<\/strong>, aunque eso a muchos les cueste hasta la vida. En el caso del compositor, como era de esperarse, recibi\u00f3 amenazas contra su vida y tuvo que irse a Estados Unidos como <strong>asilado pol\u00edtico<\/strong>, territorio en el que a\u00fan vive.<\/p>\n\n\n\n<p>Al inicio del Paro Nacional escrib\u00ed sobre la canci\u00f3n de Jos\u00e9 A. Morales <a href=\"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/2021\/04\/28\/ayer-me-echaron-del-pueblo-paronacional28a\/\">\u00abAyer me echaron del pueblo\u00bb<\/a>, les invito a leerla.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 le estar\u00e1 pasando a nuestro pa\u00eds?<\/h2>\n\n\n\n<p><em><strong>Hay que sacar al diablo, no hay m\u00e1s que hacer.<\/strong><\/em> Esta es la frase con la que termina la estrofa antes del inicio del coro. Cuando comenzaba el paro nacional, tuve la oportunidad de hablar del tema con mis estudiantes entre 11 y 18 a\u00f1os y preguntarles <strong>cu\u00e1l es ese diablo<\/strong> que hay que sacar de Colombia para que mejore nuestra situaci\u00f3n.<\/p>\n\n\n\n<p>Fueron varias las respuestas,  <strong>personajes p\u00fablicos<\/strong> que tanto da\u00f1o le hacen a la sociedad fueron mencionados, la <strong>corrupci\u00f3n<\/strong> que d\u00eda a d\u00eda nos afecta, la <strong>falta de empat\u00eda<\/strong> que tenemos como sociedad y esa <strong>violencia sin sentido<\/strong> que no evita que pase un d\u00eda en el que no se escuche en las noticias que una persona fue asesinada a manos de otro, algo tan triste como lo es nuestra indiferencia al normalizar estos actos repudiables.<\/p>\n\n\n\n<p><strong><em>Hay que parar la guerra con la canci\u00f3n, porque solo el bambuco tiene permiso de hacer llorar el alma de la emoci\u00f3n. <\/em><\/strong>Este mensaje esperanzador es lo que conmueve de la obra de <strong>Eugenio Arellano<\/strong>, pero que no evita pensar en que han pasado <strong>32 a\u00f1os<\/strong> desde su estreno y la verdad nos seguimos preguntando: <strong><em>qu\u00e9 le estar\u00e1 pasando a nuestro pa\u00eds\u2026<\/em><\/strong> Avanza el tiempo, pero no progresamos, es triste, pero es cierto y duele porque todos somos parte de Colombia y en el quehacer de cada uno est\u00e1 la posibilidad de cambiar para bien o para mal. Toda acci\u00f3n tiene una reacci\u00f3n y lo que hacemos hoy afecta y afectar\u00e1 a los que nos rodean. <strong>Hagan su elecci\u00f3n<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Beatriz y Gerardo Arellano - Hay que sacar el diablo (1989)\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/m5-U84s_BaY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A mes y medio del inicio del Paro Nacional, he querido escribir sobre Hay que sacar al diablo, bambuco escrito en 1989, pero con un mensaje que se mantiene actual. Eugenio Arellano es el nombre del compositor de esta canci\u00f3n que se estren\u00f3 en el \u201cPrimer encuentro de la M\u00fasica Colombiana\u201d celebrado en la ciudad &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/2021\/06\/11\/hay-que-sacar-al-diablo\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":44,"featured_media":80,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-79","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","item-wrap"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/files\/2021\/06\/Hay-que-sacar-al-diablo-scaled.jpg","_links":{"self":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/posts\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":2,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"predecessor-version":[{"id":82,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/posts\/79\/revisions\/82"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/media\/80"}],"wp:attachment":[{"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.vanguardia.com\/al-compas-de-juan\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}